{"id":835814,"date":"2024-06-29T12:58:05","date_gmt":"2024-06-29T10:58:05","guid":{"rendered":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/"},"modified":"2025-05-09T10:25:23","modified_gmt":"2025-05-09T08:25:23","slug":"privacy-e-cookie-policy","status":"publish","type":"page","link":"https:\/\/www.liscianigiochi.com\/de\/privacy-e-cookie-policy\/","title":{"rendered":"Privacy e cookie policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"835814\" class=\"elementor elementor-835814 elementor-660775\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1ac8ea e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"f1ac8ea\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf58fa elementor-widget elementor-widget-heading\" data-id=\"ecf58fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informationen \u00fcber die Verarbeitung personenbezogener Daten  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2aeb3d elementor-widget elementor-widget-text-editor\" data-id=\"f2aeb3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Warum dieses Dokument<\/h4><p>LISCIANIGIOCHI S.P.A. (im Folgenden auch LISCIANIGIOCHI, &#8220;Unternehmen&#8221; oder &#8220;Eigent\u00fcmer&#8221;) setzt sich f\u00fcr die Achtung und den Schutz der Privatsph\u00e4re ein und m\u00f6chte eine klare und transparente Vorstellung davon vermitteln, welche Informationen \u00fcber Einzelpersonen gesammelt und verarbeitet werden: Kunden und Benutzer, die auf der Website surfen, Eink\u00e4ufe t\u00e4tigen, den Newsletter abonnieren oder LISCIANIGIOCHI um Unterst\u00fctzung bitten.<\/p><p>Nach der vollst\u00e4ndigen Umsetzung der Allgemeinen Datenschutzverordnung 2016\/679 (die sogenannte &#8220;GDPR&#8221; oder &#8220;Verordnung&#8221;) in der gesamten Europ\u00e4ischen Union und der nationalen Gesetzgebung (Gesetzesdekret 196\/2003, ge\u00e4ndert durch Gesetzesdekret 101\/2018) hat sich LISCIANIGIOCHI die folgenden Ziele gesetzt:<br \/>&#8211; sicherstellen, dass die betroffenen Personen verstehen, welche personenbezogenen Daten gesammelt werden, f\u00fcr welche Zwecke und f\u00fcr wie lange;<br \/>&#8211; klar und transparent darlegen, wie die von den Betroffenen zur Verf\u00fcgung gestellten personenbezogenen Daten verwendet werden und mit wem sie geteilt werden, um einen immer effizienteren Service anzubieten;<br \/>&#8211; die betroffenen Personen \u00fcber ihre Rechte und Wahlm\u00f6glichkeiten im Zusammenhang mit der Verarbeitung personenbezogener Daten aufzukl\u00e4ren, um einerseits eine bessere Kontrolle \u00fcber sie und andererseits einen besseren Schutz seitens der an der Verarbeitung Beteiligten zu gew\u00e4hrleisten.<\/p><h4>\u00a0<\/h4><h4>Privacy f\u00fcr Minderj\u00e4hrige<\/h4><p>Die Registrierung ist nur Nutzern erlaubt, die das 18. Lebensjahr vollendet haben.<br \/>LISCIANIGIOCHI S.p.A. lehnt jede Verantwortung f\u00fcr den Fall ab, dass der Benutzer falsche oder unwahre Daten angibt oder sich auf Dritte, auch Minderj\u00e4hrige, bezieht, f\u00fcr die er nicht legitimiert und\/oder ausdr\u00fccklich befugt ist, diese Daten zu \u00fcbermitteln und seine Zustimmung zur Behandlung zu geben. Der Nutzer \u00fcbernimmt die volle Verantwortung f\u00fcr ein solches Verhalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cb2b2e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"9cb2b2e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-269c443\" data-id=\"269c443\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8148827 elementor-widget elementor-widget-accordion\" data-id=\"8148827\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1351\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1351\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Website-Navigation und Cookie-Richtlinie<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1351\"><p><strong>INFORMATIONEN \u00dcBER <\/strong><strong>VERARBEITUNG PERSONENBEZOGENER DATEN <\/strong><strong>WEBSITE UND COOKIE-RICHTLINIE<\/strong><\/p><p><strong>gem\u00e4\u00df Art. 13 der Verordnung (EU) 2016\/679 <\/strong><\/p><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\" \/><\/div><div style=\"width: 92%;\"><p>DATENVERANTWORTLICHER <strong>UND<\/strong> PERS\u00d6NLICHER <strong>DATENVERARBEITER DPO LISCIANI<\/strong><strong>GIOCHI S.P.A. <\/strong>ist der Datenverantwortliche f\u00fcr die \u00fcber die Website <strong>www.liscianigroup.com<\/strong> verarbeiteten personenbezogenen Daten <strong>.<\/strong> Der eingetragene Sitz befindet sich in <strong>Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te)<\/strong>, P.IVA 00723030672. F\u00fcr alle Fragen zum Datenschutz wenden Sie sich bitte an die folgende E-Mail-Adresse: <a href=\"mailto:privacy@liscianigiochi.it\"><strong>privacy@liscianigiochi.it<\/strong><\/a>oder die Telefonnummer <a href=\"tel:+3908612311\">+39 0861 2311<\/a><strong>.<\/strong>Der Datenschutzbeauftragte kann schriftlich an die E-Mail-Adresse <a href=\"mailto:dpo@liscianigiochi.it\">dpo@liscianigiochi.it<\/a> kontaktiert werden. Die Website der Institution hat folgende Adresse: <strong>https:\/\/www.liscianigroup.com<\/strong><\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-2.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>BESCHREIBUNG DER VERARBEITUNG UND <\/strong><strong>KATEGORIEN DER<\/strong>BETROFFENENPERSONENDie \u00fcber die Website erhobenen personenbezogenen Daten werden in voller \u00dcbereinstimmung mit den geltenden Rechtsvorschriften verarbeitet, wobei die Sicherheit, die Vertraulichkeit und der Schutz der in ihrem Besitz befindlichen Daten unter Wahrung der Grundrechte und -freiheiten der betroffenen Personen gem\u00e4\u00df der Europ\u00e4ischen Verordnung 2016\/679, im Folgenden GDPR genannt, gew\u00e4hrleistet werden.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-3.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ART DER ERFASSTEN DATEN <\/strong>Die Daten werden bei der betroffenen Person erhoben. Die f\u00fcr den Betrieb dieser Website verwendeten Computersysteme und Softwareverfahren erfassen w\u00e4hrend ihres normalen Betriebs einige personenbezogene Daten, deren \u00dcbermittlung mit der Nutzung des Internets einhergeht. Zu den personenbezogenen Daten, die von dieser Website erfasst werden, geh\u00f6ren: technische, statistische und profilbildende Cookies, Daten zur Nutzung der Website, die auf der Website verbrachte Zeit. Zu den verschiedenen Informationen, die wir sammeln, geh\u00f6ren Informationen, die Sie als Person identifizieren k\u00f6nnen (&#8220;personenbezogene Daten&#8221;). Au\u00dferdem k\u00f6nnen wir &#8211; gegebenenfalls mit Ihrer Zustimmung &#8211; bestimmte Daten \u00fcber Ihr Ger\u00e4t verarbeiten, z.B. die anonymisierte IP-Adresse Ihres Ger\u00e4ts und die Aktivit\u00e4t in Bezug auf die von Ihnen genutzten Dienste. Die \u00fcber die Website verarbeiteten personenbezogenen Daten sind wie folgt: A. <strong>Automatisch erhobene Browsing-Daten: <\/strong>Diese Informationen werden nicht erhoben, um mit identifizierten Interessenten in Verbindung gebracht zu werden, k\u00f6nnten aber aufgrund ihrer Beschaffenheit durch die Verarbeitung und Verkn\u00fcpfung mit Daten im Besitz von Dritten die Identifizierung von Browsing-Nutzern erm\u00f6glichen. Zu dieser Datenkategorie geh\u00f6ren die &#8220;IP-Adressen&#8221; oder Domain-Namen der Computer, die von den Nutzern verwendet werden, die sich mit der Website verbinden, sowie die URI (Uniform Resource Identifier) Notationsadressen der angeforderten Ressourcen. Die IP-Adressen werden in &#8220;anonymisierter&#8221; Form gespeichert. Die sichtbaren Teile der Informationen werden ausschlie\u00dflich dazu verwendet, anonyme statistische Informationen \u00fcber die Nutzung der Website zu erhalten und das ordnungsgem\u00e4\u00dfe Funktionieren der Website von LISCIANIGIOCHI S.p.A. zu \u00fcberpr\u00fcfen. B. Cookies <strong>:<\/strong> Die Website verwendet einige Cookies, und die damit gesammelten Daten k\u00f6nnen f\u00fcr den Zugriff auf Teile der Website oder f\u00fcr statistische und profilbildende Zwecke verwendet werden oder um das Surfen in Zukunft angenehmer und effizienter zu gestalten, indem versucht wird, das Verhalten der Benutzer zu bewerten und das Inhaltsangebot entsprechend ihrem Verhalten zu \u00e4ndern. Weitere Informationen \u00fcber Cookies finden Sie im Abschnitt &#8220;Cookie-Richtlinie&#8221; weiter unten. C. <strong>Daten im Zusammenhang mit Websites, Diensten Dritter, Plug-Ins<\/strong>: Die Website kann Links zu anderen Websites oder Anwendungen enthalten. Die Website enth\u00e4lt auch Plug-ins und\/oder Schaltfl\u00e4chen f\u00fcr soziale Netzwerke, um das einfache Teilen von Inhalten in Ihren bevorzugten sozialen Netzwerken zu erm\u00f6glichen. Diese Plug-ins sind so programmiert, dass sie keine Cookies setzen, wenn Sie die Seite aufrufen, um Ihre Privatsph\u00e4re zu sch\u00fctzen. Cookies werden nur dann gesetzt, wenn dies von den sozialen Netzwerken vorgesehen ist, wenn der Benutzer das Plug-in tats\u00e4chlich und freiwillig verwendet. Bitte beachten Sie, dass, wenn der Nutzer navigiert, w\u00e4hrend er bei dem sozialen Netzwerk angemeldet ist, er der Verwendung von Cookies, die \u00fcber diese Website \u00fcbermittelt werden, bereits bei der Anmeldung bei dem sozialen Netzwerk zugestimmt hat: Die Dienste k\u00f6nnen verwendet werden, um den Verkehr dieser Website zu analysieren, der m\u00f6glicherweise pers\u00f6nliche Daten der Nutzer enth\u00e4lt, um Teile des Verkehrs, Nachrichten und Inhalte herauszufiltern, die als SPAM erkannt werden (Google reCAPTCHA, SPAM-Schutzdienst von Google Inc.). Die Sammlung und Verwendung von Informationen, die mit Hilfe von Plug-ins gewonnen werden, unterliegen den jeweiligen Datenschutzrichtlinien der sozialen Netzwerke, die Sie bitte einsehen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-4.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ZWECK DER VERARBEITUNGDie<\/strong>Website fragt bestimmte Informationen vom Browser ab, um einen qualitativ hochwertigen Service anbieten zu k\u00f6nnen. Dabei handelt es sich um Browsing-Pr\u00e4ferenzen, Logins und Cookies, die f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren der Website und f\u00fcr einen besseren Service verwendet werden. Der Data Controller kann die Daten verarbeiten, um &#8211; die Website und die Dienste zu verwalten und f\u00fcr interne Abl\u00e4ufe zu nutzen, einschlie\u00dflich der Fehlerbehebung und, wenn dies legitim ist, f\u00fcr Datenanalysen, Tests, statistische Zwecke und Umfragen; &#8211; die Website zu verbessern und daf\u00fcr zu sorgen, dass die Inhalte auf die effektivste Art und Weise pr\u00e4sentiert werden; &#8211; wenn dies legitim ist, f\u00fcr die Trendbeobachtung, das Marketing und die Werbung; &#8211; die Website sicher zu halten und f\u00fcr die Haftungsbeurteilung im Falle von Computerkriminalit\u00e4t gegen die Website und den Rechtsschutz.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-5.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTLICHE GRUNDLAGENDie<\/strong>Verwendung von technischen Cookies bedarf keiner Zustimmung, da sie f\u00fcr die Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen (Art. 6 Abs. 1.b der DSGVO) des f\u00fcr die Verarbeitung Verantwortlichen erforderlich ist, damit die Funktionalit\u00e4ten der Website des Unternehmens infolge der vom Nutzer durchgef\u00fchrten Navigation genutzt und genossen werden k\u00f6nnen. Die Verwendung von Profiling-Cookies erfolgt mit der Zustimmung der betroffenen Person (Art. 6 Abs. 1.a der DSGVO).<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-6.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RICHTLINIE ZU COOKIES UND \u00c4HNLICHEN TECHNOLOGIEN<\/strong><script id=\"CookieDeclaration\" src=\"https:\/\/consent.cookiebot.com\/fe345f49-7359-4e43-8955-94e7b5b0be1b\/cd.js\" type=\"text\/javascript\" async=\"\"><\/script><\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-7.png\" \/><\/div><div style=\"width: 92%;\"><p>EMPF\u00c4NGER <strong>UND KATEGORIEN VON EMPF\u00c4NGERNDie<\/strong>vom Datenverwalter verarbeiteten personenbezogenen Daten werden nicht weitergegeben. Sie k\u00f6nnen jedoch an Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen und an externe Personen, die mit ihm zusammenarbeiten und als Datenverarbeiter benannt sind (z.B. dritte technische Dienstleister, Postkuriere, Hosting-Provider, IT-Unternehmen, Kommunikationsagenturen, Mitarbeiter der Website-Verwaltung, Plattform f\u00fcr die Verwaltung von Cookies und Website-Zustimmungen) oder zur Verarbeitung der Daten befugt sind, da sie unter der Aufsicht des f\u00fcr die Verarbeitung Verantwortlichen t\u00e4tig sind, oder an andere Personen, die an der Organisation dieser Website beteiligt sind (Verwaltungs-, Vertriebs-, Marketing-, Rechts- und Systemadministratoren), \u00fcbermittelt werden. Schlie\u00dflich k\u00f6nnen die Daten an die Personen weitergegeben werden, die aufgrund von Gesetzen, Verordnungen und EU-Rechtsvorschriften rechtm\u00e4\u00dfig auf sie zugreifen k\u00f6nnen. Aus Gr\u00fcnden der Einhaltung gesetzlicher Vorschriften oder zur Feststellung der Verantwortlichkeit im Falle von Computerkriminalit\u00e4t zum Nachteil der Website k\u00f6nnen die Daten an Dritte weitergegeben oder ihnen zugeordnet werden. Eine aktualisierte Liste der verantwortlichen Personen kann jederzeit beim Data Controller angefordert werden. Dies gilt unbeschadet der Verpflichtung von LISCIANIGIOCHI S.p.a., Daten auf konkrete Anfrage an Beh\u00f6rden weiterzugeben.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-8.png\" \/><\/div><div style=\"width: 92%;\"><p>Die Daten werden in den Gesch\u00e4ftsr\u00e4umen des f\u00fcr die Verarbeitung Verantwortlichen und an jedem anderen Ort verarbeitet, an dem sich die an der Verarbeitung beteiligten Parteien befinden. Der f\u00fcr die Verarbeitung Verantwortliche \u00fcbermittelt diese personenbezogenen Daten daher nicht an <strong>Drittl\u00e4nder<\/strong>oder internationale Organisationen. Er beh\u00e4lt sich jedoch die M\u00f6glichkeit vor, Cloud-Dienste zu nutzen; in diesem Fall werden die Dienstleister unter denjenigen ausgew\u00e4hlt, die angemessene Garantien bieten, wie in Artikel 46 GDPR 2016\/679 vorgesehen. F\u00fcr die Verarbeitung der Informationen und Daten, die an diese Stellen weitergegeben werden k\u00f6nnen, gilt ein gleichwertiges Schutzniveau wie f\u00fcr die Verarbeitung der personenbezogenen Daten der Mitarbeiter. In jedem Fall werden nur die Daten \u00fcbermittelt, die f\u00fcr die Verfolgung der beabsichtigten Zwecke erforderlich sind, und es werden die vorgesehenen Regulierungsinstrumente angewandt.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-9.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DAUER DER<\/strong>VERARBEITUNGIn \u00dcbereinstimmung mit dem Grundsatz der Speicherbegrenzung (Art. 5, GDPR) wird die \u00dcberpr\u00fcfung der Veralterung der gespeicherten Daten in Bezug auf die Zwecke, f\u00fcr die sie erhoben wurden, regelm\u00e4\u00dfig durchgef\u00fchrt. Insbesondere: a) automatisch erhobene Daten werden nur so lange verarbeitet, wie es unbedingt notwendig ist, um statistische Informationen \u00fcber die Nutzung der Website zu erhalten und ihren ordnungsgem\u00e4\u00dfen Betrieb zu \u00fcberpr\u00fcfen, auch zu Sicherheitszwecken oder in \u00dcbereinstimmung mit den gesetzlich vorgesehenen Fristen; b) vom Nutzer freiwillig zur Verf\u00fcgung gestellte Daten werden f\u00fcr einen Zeitraum aufbewahrt, der die Erreichung der Zwecke, f\u00fcr die sie verarbeitet werden, nicht \u00fcbersteigt oder in \u00dcbereinstimmung mit den gesetzlich vorgesehenen Fristen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-10.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>METHODEN UND ART DER<\/strong>DATENVERARBEITUNGDie Daten werden rechtm\u00e4\u00dfig und nach Treu und Glauben f\u00fcr die oben genannten Zwecke unter Einhaltung der in Artikel 5(1) der DSGVO festgelegten Grunds\u00e4tze und Anforderungen erhoben und gespeichert. Die Verarbeitung der personenbezogenen Daten erfolgt mittels manueller, computergest\u00fctzter und telematischer Hilfsmittel mit einer Logik, die sich streng an den eigentlichen Zwecken orientiert und in jedem Fall die Sicherheit und Vertraulichkeit gew\u00e4hrleistet. Die Bereitstellung von Daten f\u00fcr die oben genannten Zwecke ist v\u00f6llig freiwillig. Die Weigerung der betroffenen Person, personenbezogene Daten zur Verf\u00fcgung zu stellen, das Fehlen einer Einwilligung oder deren Widerruf f\u00fcr einen oder mehrere Zwecke macht es unm\u00f6glich, die damit verbundenen Dienstleistungen in Anspruch zu nehmen. Die betroffene Person kann sich weigern, dem f\u00fcr die Datenverarbeitung Verantwortlichen ihre Navigationsdaten zu \u00fcbermitteln. Dazu muss er\/sie die Cookies deaktivieren, indem er\/sie die Anweisungen des verwendeten Browsers befolgt. Die Deaktivierung von Cookies kann die Navigation und die Nutzung der Funktionen der Website verschlechtern oder verhindern.<\/p><hr \/><p><strong>SICHERHEITSMASSNAHMEN<\/strong> Die \u00dcbertragung, Speicherung und Verarbeitung der \u00fcber die Website gesammelten Daten der betroffenen Person wird durch geeignete technische und sicherheitstechnische Massnahmen gew\u00e4hrleistet, insbesondere: Alle Informationen der betroffenen Person werden mit den vom Benutzer gew\u00e4hlten Zugangsschl\u00fcsseln gesch\u00fctzt, Passw\u00f6rter werden nicht im Klartext aufgezeichnet. Die Website ist mit einer verschl\u00fcsselten HTTPS-Verbindung ausgestattet. Es wird eine sichere E-Commerce-Plattform mit integrierten Sicherheitsprotokollen verwendet. Es werden komplexe Passw\u00f6rter verwendet. Die Daten werden auf einem sicheren Server erfasst, gespeichert und gepflegt, der durch eine Firewall gesch\u00fctzt ist und sich physisch in einer zugangskontrollierten Webfarm in der EU befindet.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-11.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTE DER<\/strong>BETROFFENENIn \u00dcbereinstimmung mit, innerhalb der Grenzen und unter den Bedingungen, die in der Gesetzgebung zum Schutz personenbezogener Daten f\u00fcr die Aus\u00fcbung der Rechte der Betroffenen (Artikel 15 bis 22) vorgesehen sind, k\u00f6nnen die Nutzer als Betroffene in Bezug auf die in diesem Informationsschreiben behandelten Verarbeitungen bestimmte Rechte in Bezug auf die vom Datenverantwortlichen verarbeiteten Daten aus\u00fcben. Insbesondere hat der Betroffene das Recht auf: &#8211; Widerruf der Einwilligung zu jeder Zeit &#8211; Widerspruch gegen die Verarbeitung der eigenen Daten &#8211; Zugang zu den eigenen Daten &#8211; \u00dcberpr\u00fcfung und Berichtigung &#8211; Einschr\u00e4nkung der Verarbeitung &#8211; L\u00f6schung oder Entfernung der eigenen personenbezogenen Daten &#8211; \u00dcbertragbarkeit Dar\u00fcber hinaus hat die betroffene Person das Recht, bei der zust\u00e4ndigen Datenschutzaufsichtsbeh\u00f6rde eine Beschwerde einzureichen oder rechtliche Schritte einzuleiten, wenn sie der Ansicht ist, dass die sie betreffenden Verarbeitungen gegen die Bestimmungen der DSGVO versto\u00dfen, gem\u00e4\u00df Artikel 77 der DSGVO. Wenn Sie weitere Informationen \u00fcber die Verarbeitung Ihrer personenbezogenen Daten anfordern oder Ihre<strong>Rechte<\/strong> aus\u00fcben m\u00f6chten, <strong>k\u00f6nnen<\/strong> Sie sich schriftlich an <a href=\"mailto:privacy@liscianigiochi.it\"><strong>privacy@liscianigiochi.it<\/strong><\/a> unter Verwendung des<strong> &#8220;<\/strong><a href=\"https:\/\/d.docs.live.net\/9970872860be413a\/MG-FLO-LU\/S%5e0I%20CONSULTING%20TERAMO%2021.06.21\/LISCIANI%20GIOGHI%20SPA\/NUOVO%20SITO%20WEB\/BOZZA%20PRIVACY_COOKIE%20POLICY\/7.%20MODULO%20ESERCIZIO%20DIRITTI.docx\"><strong>Formular zur Aus\u00fcbung von Rechten<\/strong><\/a><strong>&#8220;.<\/strong> Die Antr\u00e4ge werden kostenlos eingereicht und von dem f\u00fcr die Verarbeitung Verantwortlichen so schnell wie m\u00f6glich, in jedem Fall aber innerhalb eines Monats, bearbeitet.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-12.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>AUTOMATISIERTE VERARBEITUNGIn<\/strong>keinem Fall f\u00fchrt der f\u00fcr die Verarbeitung Verantwortliche in Bezug auf die nachstehend aufgef\u00fchrten Verarbeitungen Verarbeitungen durch, die aus automatisierten Entscheidungsprozessen in Bezug auf die Daten nat\u00fcrlicher Personen bestehen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-13.png\" \/><\/div><div style=\"width: 92%;\"><p>\u00c4NDERUNGEN AN DIESER <strong>DATENSCHUTZPOLITIKDer<\/strong>f\u00fcr die Verarbeitung Verantwortliche beh\u00e4lt sich das Recht vor, jederzeit \u00c4nderungen an dieser Datenschutzpolitik vorzunehmen, indem er die Nutzer per E-Mail und auf der Website dar\u00fcber informiert. Der f\u00fcr die Verarbeitung Verantwortliche wird gegebenenfalls die Zustimmung der betroffenen Person erneut einholen. Letzte \u00c4nderung: 14\/10\/2021<\/p><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1352\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1352\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Informationen \u00fcber die Verarbeitung personenbezogener Daten von Nutzern im privaten Bereich der Website und der App<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1352\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1352\"><p><strong>DATENSCHUTZBESTIMMUNGEN F\u00dcR DIE VERARBEITUNG PERSONENBEZOGENER DATEN VON NUTZERINNEN UND NUTZERN DES GESCH\u00dcTZTEN BEREICHS WEBSITE UND APP<\/strong><\/p><p><strong>(reservierter Bereich, Helpdesk, App-\u00d6kosystem, Online-Kontaktformular, Online-Shopping) gem\u00e4\u00df Artikel 13 der Verordnung (EU) 2016\/679 <\/strong><\/p><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DATENVERANTWORTLICHER UND KONTAKTANGABEN<\/strong><\/p><p>L<strong>ISCIANI GIOCHI S.P.A. <\/strong>ist der Verantwortliche f\u00fcr die personenbezogenen Daten, die \u00fcber die Website www.liscianigiochi.com und innerhalb des LISCIANIGIOCHI App Ecosystems verarbeitet werden. Der Sitz befindet sich in Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te), P.IVA 00723030672.<strong><br \/>F\u00fcr alle Aspekte des Datenschutzes k\u00f6nnen Sie sich an die folgende E-Mail-Adresse wenden: <\/strong><strong>privacy@liscianigiochi.itovvero die Telefonnummer +39 0861 2311. Die institutionelle Website hat die folgende Adresse:<strong>https:<\/strong> \/\/www.liscianigroup.com <\/strong><\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-14.jpg\" \/><\/div><div style=\"width: 92%;\"><p><strong>DATENSCHUTZ F\u00dcR MINDERJ\u00c4HRIGE<\/strong><\/p><p>Die Registrierung ist nur Nutzern gestattet, die das 18. Lebensjahr vollendet haben; daher d\u00fcrfen Minderj\u00e4hrige keine pers\u00f6nlichen Daten an LISCIANIGIOCHI \u00fcbermitteln. Aus diesem Grund sorgen die Eltern und\/oder die Erziehungsberechtigten f\u00fcr ihre eigene Registrierung im gesch\u00fctzten Bereich und\/oder f\u00fcr die Definition eines oder mehrerer Spielerprofile (USER). Minderj\u00e4hrige werden gebeten, bei der Erstellung eines Profils und\/oder Avatars nicht ihren echten Vor- und Nachnamen zu verwenden.<br \/>Wenn ein Erziehungsberechtigter trotz des hier ausgesprochenen Verbots davon Kenntnis erlangt, dass sein minderj\u00e4hriges Kind uns direkt Informationen zur Verf\u00fcgung gestellt hat, muss er uns unter der E-Mail-Adresse privacy@liscianigiochi.it f\u00fcr die L\u00f6schung\/\u00c4nderung kontaktieren. LISCIANIGIOCHI lehnt jede Verantwortung f\u00fcr den Fall ab, dass der Benutzer falsche oder unwahre Daten angibt oder diese mit Dritten, auch Minderj\u00e4hrigen, in Verbindung bringt, f\u00fcr die er nicht legitimiert und\/oder ausdr\u00fccklich zur Erteilung und zur ausdr\u00fccklichen Zustimmung zur Behandlung befugt ist. Der Nutzer \u00fcbernimmt die volle Verantwortung f\u00fcr ein solches Verhalten.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-2.png\" \/><\/div><div style=\"width: 92%;\"><p>B<strong>ESCHREIBUNG DER VERARBEITUNG UND KATEGORIEN VON INTERESSENTEN<\/strong> Diese Erkl\u00e4rung erl\u00e4utert, wie personenbezogene Daten \u00fcber Nutzer, die in den verschiedenen Bereichen der Unternehmenswebsite und bei der Nutzung der Liscianigiochi-App erhoben werden, verwaltet werden. Insbesondere werden personenbezogene Daten durch:<\/p><p>a) das Ausf\u00fcllen des Anmeldeformulars f\u00fcr den reservierten Bereich;<br \/>(b) die Bitte um Unterst\u00fctzung durch den Helpdesk-Service;<br \/>c) den Online-Kauf von Produkten (Auftragsverwaltung, Produktverkauf und -lieferung, Verwaltung von R\u00fccksendungen und Garantien und andere f\u00fcr den Verkauf von Produkten \u00fcber den elektronischen Handel notwendige Aktivit\u00e4ten) mit oder ohne Zugang zum reservierten Bereich;<br \/>d) Kontoregistrierung f\u00fcr die Nutzung des Liscianigiochi App-\u00d6kosystems und f\u00fcr die Nutzung des Ger\u00e4ts (Tablet, Roboter, Telefon) durch die Spieler;<br \/>e) das Ausf\u00fcllen des Online-Kontaktformulars;<br \/>Die gesammelten personenbezogenen Daten werden in voller \u00dcbereinstimmung mit der geltenden Gesetzgebung verarbeitet, wobei die Sicherheit, die Vertraulichkeit und der Schutz der Daten, die sich in ihrem Besitz befinden, unter Beachtung der Grundrechte und -freiheiten, die den betroffenen Personen zuerkannt werden, in \u00dcbereinstimmung mit der Europ\u00e4ischen Verordnung 2016\/679 (GDPR) gew\u00e4hrleistet werden.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-3.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ARTEN DER ERHOBENEN DATEN UND HERKUNFT DER DATEN<\/strong><\/p><p>Die Daten werden von der betroffenen Person erhoben und direkt bei der Erstellung eines Kontos im reservierten Bereich, bei der Bitte um Unterst\u00fctzung, beim Kauf, bei der Registrierung auf einem Tablet, bei der Nutzung von Apps, beim Senden einer Kontaktanfrage angegeben.<\/p><p>Erfasste Daten: Vorname, Nachname, E-Mail, Telefon, Adresse, Art des Nutzers und Beruf, Umsatzsteueridentifikationsnummer, Steuernummer, Geburtsdatum, Systemprotokoll, Daten \u00fcber get\u00e4tigte Eink\u00e4ufe, Zahlungsart. Insbesondere in Bezug auf die Nutzung von Apps auf Ecosistema LISCIANIGIOCHI werden die folgenden Kategorien personenbezogener Daten verarbeitet:<\/p><p><strong> A. <\/strong><br \/>L<strong> isciani&#8217;s APP ECOSYSTEM: <\/strong> &#8211; GEMEINSAME DATEN: Vorname, Nachname, Geburtsdatum, E-Mail-Adresse, Telefonnummer, Postanschrift der registrierten Nutzer; Daten, die im Spielerprofil (USER) eingegeben werden, wie z.B. Bild, Name oder Spielpseudonym. Das Profil eines jeden Spielers kann durch das Einf\u00fcgen eines Bildes personalisiert werden: LISCIANIGIOCHI r\u00e4t davon ab, Fotos von Minderj\u00e4hrigen in das Spielerprofil hochzuladen. <br \/>&#8211; INFORMATISCHE DATEN: Basisdaten der Markenger\u00e4te (Telefone, Tablets, Roboter) und der mit ihnen verbundenen \u00fcbergeordneten Ger\u00e4te (z.B. Mobiltelefon); Freundschaftsstruktur zwischen den verschiedenen Nicknames; Zugriffs-\/Exit-Protokolle.<br \/>&#8211; ANWENDUNGSDATEN: Identifizierung der aus dem LISCIANIGIOCHI-Store heruntergeladenen Anwendungen und Protokoll der spezifischen Anwendung, die vom Spieler verwendet wird.<br \/><strong> B. <\/strong>APP TUTOR<strong>: <\/strong>Der APP TUTOR sammelt Informationen \u00fcber die Aktivit\u00e4ten, um es den Eltern zu erm\u00f6glichen, die Spielaktivit\u00e4ten der Kinder zu \u00fcberwachen (Spielbildschirme, erzielte Ergebnisse und Punkte, Sprachaufnahmen). LISCIANIGIOCHI verarbeitet diese Informationen nicht, sondern speichert sie lediglich und stellt sie dem registrierten Benutzer zur \u00dcberpr\u00fcfung zur Verf\u00fcgung.<br \/>Verwendung von Mikrofon und Kamera: Einige APPs verwenden das Mikrofon und die Kamera f\u00fcr einige Spielfunktionen und speichern die gesammelten Informationen lokal (d.h. in einem Speicherort des Ger\u00e4ts), die somit in keiner Weise in die Verf\u00fcgbarkeit von LISCIANIGIOCHI einflie\u00dfen, auch nicht zu Zwecken der einfachen Speicherung; am gleichen Ort werden Sprachaufnahmen oder Bilder gespeichert, die mit dem Ger\u00e4t au\u00dferhalb des Spielkontexts gesammelt werden.<br \/>Alle diese Informationen k\u00f6nnen jederzeit vom registrierten Benutzer verwaltet und gel\u00f6scht werden. Es liegt daher in der Verantwortung des Benutzers, daran zu denken,<strong>die pers\u00f6nlichen Daten, die APPs oder Spieler auf dem Ger\u00e4t speichern, zu l\u00f6schen, bevor er sie entsorgt oder an Dritte weitergibt.<\/strong><\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-4.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ZWECK DER VERARBEITUNG<\/strong><\/p><p>Personenbezogene Daten werden f\u00fcr die folgenden Zwecke verarbeitet:<br \/>1. den Zugang zum reservierten Bereich zu genehmigen und die erforderlichen Dienste bereitzustellen, das erstellte Konto zu pflegen und zu verwalten;<br \/>2. die betreffende Person dar\u00fcber informieren, dass Inhalte und Dokumente von Interesse im reservierten Bereich verf\u00fcgbar sind;<br \/>3. Kundenunterst\u00fctzung f\u00fcr seine Produkte\/Dienstleistungen anbieten;<br \/>4. zur Erf\u00fcllung aller gesetzlichen Verpflichtungen im Zusammenhang mit den relevanten administrativen, buchhalterischen, steuerlichen und finanziellen Vorg\u00e4ngen im Zusammenhang mit dem angebotenen Produkt oder der Dienstleistung;<br \/>5. Bei Verlust der Zugangsdaten aktivieren Sie das Verfahren, mit dem das Passwort wiederhergestellt und zur\u00fcckgesetzt werden kann;<br \/>6. den Schutz vertraglicher Rechte und die Verfolgung der legitimen Interessen des f\u00fcr die Verarbeitung Verantwortlichen, einschlie\u00dflich &#8211; falls zutreffend &#8211; der Geltendmachung oder Verteidigung eines Rechts vor Gericht;<\/p><p>7. die Bearbeitung von Informationsanfragen zu den angebotenen Produkten\/Dienstleistungen und von kommerziellen oder anderen Anfragen, die durch das Ausf\u00fcllen der Formulare gestellt werden; 8. den Online-Kauf von Produkten\/Dienstleistungen und den Abschluss des Kaufvertrags durch E-Commerce zu erm\u00f6glichen; 9. die Bearbeitung von Berichten und internen Kontrollen; 10.<br \/>die Sicherheit innerhalb der Website und des LISCIANIGIOCHI APP-\u00d6kosystems zu gew\u00e4hrleisten, betr\u00fcgerische oder illegale Nutzungen zu verwalten und zu blockieren; 11. die Nutzung der im LISCIANIGIOCHI-\u00d6kosystem verf\u00fcgbaren APPs zu erm\u00f6glichen (bitte beachten Sie, dass f\u00fcr die Nutzung von Kamera und Voice-Recorder die vorherige Zustimmung des Nutzers erforderlich ist.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-5.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTSGRUNDLAGE<\/strong><\/p><p>In Bezug auf die Verarbeitung personenbezogener Daten f\u00fcr die im vorherigen Punkt beschriebenen Zwecke sind die Rechtsgrundlagen: &#8211; die Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen (Art. 6 Abs.1<\/p><p>.b der DSGVO) f\u00fcr die Zwecke 1, 2, 3, 5, 7, 8, 11; &#8211; die Erf\u00fcllung rechtlicher Verpflichtungen (Art. 6 Abs.1.c der DSGVO) f\u00fcr die Zwecke 4, 9; &#8211; die Verfolgung des berechtigten Interesses des f\u00fcr die Verarbeitung Verantwortlichen (Art. 6 Abs.1.f der DSGVO) f\u00fcr die Zwecke 6, 10.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-7.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ADRESSATEN UND KATEGORIEN<\/strong><\/p><p>Die vom f\u00fcr die Verarbeitung Verantwortlichen verarbeiteten personenbezogenen Daten werden nicht weitergegeben.<br \/>Sie k\u00f6nnen jedoch an externe Parteien weitergegeben werden, die als Datenverarbeiter benannt werden (wie z.B. dritte technische Dienstleister, Hosting-Anbieter, IT-Unternehmen, Kommunikationsagenturen, Postkuriere, Anbieter von Website-Verwaltungs- und Entwicklungsdiensten, Support-Dienste und Wartung von Servern und Netzwerken, Anbieter von Online-Shop-Infrastrukturen, Kundenbetreuungsdienste Lieferanten, die das \u00d6kosystem APP LISCIANIGIOCHI entwickeln, verwalten und pflegen und sich mit der Registrierung von Nutzern befassen) oder an Personen, die zur Verarbeitung befugt sind, da sie unter der Aufsicht des f\u00fcr die Datenverarbeitung Verantwortlichen t\u00e4tig sind, oder an andere Stellen, die an der Organisation dieser Website beteiligt sind (Verwaltung, Vertrieb, Marketing, Rechtsabteilung, Systemadministratoren).<br \/>Schlie\u00dflich k\u00f6nnen die Daten an die Personen weitergegeben werden, die aufgrund von Gesetzen, Verordnungen und EU-Vorschriften zum Zugriff auf sie berechtigt sind.<br \/>Aus Gr\u00fcnden der Einhaltung gesetzlicher Vorschriften oder zur Feststellung der Verantwortlichkeit im Falle von Computerkriminalit\u00e4t gegen die Website k\u00f6nnen die Daten an Dritte weitergegeben oder ihnen zugeordnet werden. F\u00fcr Daten im Zusammenhang mit Kreditkarten wird die Plattform Stripe verwendet (https:\/\/stripe.com\/it), die Daten werden nicht von Liscianigiochi Spa, sondern nur von dieser Plattform verarbeitet.<br \/>F\u00fcr Transaktionen, die vom Nutzer\/Interessenten \u00fcber die Stripe-Plattform durchgef\u00fchrt werden, siehe Informationen: https:\/\/stripe.com\/it. Die aktualisierte Liste der Verantwortlichen kann jederzeit beim Datenverantwortlichen angefordert werden.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-8.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>\u00dcBERWEISUNG INS AUSLAND<\/strong><\/p><p>Die Daten werden in den R\u00e4umlichkeiten des f\u00fcr die Verarbeitung Verantwortlichen und an jedem anderen Ort, an dem sich die an der Verarbeitung beteiligten Parteien befinden, verarbeitet, so dass der f\u00fcr die Verarbeitung Verantwortliche diese personenbezogenen Daten nicht an Drittl\u00e4nder oder internationale Organisationen au\u00dferhalb der EU weitergibt. Er beh\u00e4lt sich jedoch das Recht vor, Cloud-Dienste zu nutzen. In diesem Fall werden die Dienstleister unter denjenigen ausgew\u00e4hlt, die angemessene Garantien bieten, wie in Artikel 46 GDPR vorgesehen. Die Verarbeitung von Informationen und Daten, die an diese Parteien weitergegeben werden k\u00f6nnen, erfordert ein gleichwertiges Schutzniveau, wie es f\u00fcr die Verarbeitung der personenbezogenen Daten seiner Mitarbeiter gilt. In jedem Fall werden nur die Daten \u00fcbermittelt, die f\u00fcr die Verfolgung der beabsichtigten Zwecke erforderlich sind, und es werden die vorgeschriebenen Instrumente angewandt.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-9.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DAUER DER BEHANDLUNG<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche speichert und verarbeitet personenbezogene Daten f\u00fcr den Zeitraum, der zur Erf\u00fcllung der angegebenen Zwecke erforderlich ist, d.h. f\u00fcr den Zeitraum, in dem der f\u00fcr die Verarbeitung Verantwortliche den Dienst aufrechterh\u00e4lt.<br \/>Im Besonderen:<br \/>&#8211; Die Registrierungsdaten werden bis zur Schlie\u00dfung des Kontos verarbeitet, wobei die daf\u00fcr erforderliche technische Zeit ber\u00fccksichtigt wird;<br \/>&#8211; Daten, die aufgrund gesetzlicher Verpflichtungen verarbeitet werden, werden f\u00fcr 10 Jahre ab dem Ende des Vertragsverh\u00e4ltnisses gespeichert;<br \/>&#8211; Daten, die f\u00fcr die Durchf\u00fchrung von vorvertraglichen Aktivit\u00e4ten verarbeitet werden, werden im Falle eines Nichtabschlusses des Kaufs 5 Monate nach der Datenerfassung gel\u00f6scht;<br \/>&#8211; Daten, die der Benutzer freiwillig durch Ausf\u00fcllen des Formulars im Bereich &#8216;Kontakt&#8217; angibt, werden die Daten f\u00fcr maximal 12 Monate oder f\u00fcr die Dauer der Produktgarantie gespeichert (da sich Anfragen auch auf den technischen Support f\u00fcr Produkte w\u00e4hrend der Garantiezeit beziehen k\u00f6nnen);<br \/>&#8211; im Falle eines Rechtsstreits f\u00fcr die gesamte Dauer des Rechtsstreits, bis die Rechtsmittelfristen ausgesch\u00f6pft sind;<br \/>&#8211; Die Informationen \u00fcber registrierte Benutzer und Spielerprofile werden so lange aufbewahrt, wie Sie die LISCIANIGIOCHI APPs nutzen, plus 12 Monate, es sei denn, wir m\u00fcssen sie l\u00e4nger aufbewahren, um unseren steuerlichen oder rechtlichen Verpflichtungen nachzukommen oder um Beschwerden zu bearbeiten. APP-Nutzer sind diejenigen, die das LISCIANIGIOCHI-Ger\u00e4t mindestens einmal in einem Zeitraum von 12 Monaten nutzen (&#8220;aktive Konten&#8221;).<br \/>Wenn das Ger\u00e4t w\u00e4hrend eines zusammenh\u00e4ngenden Zeitraums von 12 Monaten nicht genutzt wird (&#8220;inaktives Konto&#8221;), wird der Nutzer durch eine von LISCIANIGIOCHI versandte Warn-E-Mail dar\u00fcber informiert, dass alle seine Daten nach weiteren 30 Tagen der Inaktivit\u00e4t gel\u00f6scht werden; ein erneuter Zugriff des Ger\u00e4ts auf LISCIANIGIOCHI APPs qualifiziert das Konto erneut als aktiv f\u00fcr weitere 12 Monate; &#8211; die Protokolle werden f\u00fcr einen Zeitraum von maximal 6 Monaten aufbewahrt. <br \/>Nach Ablauf dieser Fristen werden die Daten gel\u00f6scht oder anonymisiert, es sei denn, ihre weitere Aufbewahrung ist erforderlich, um entstandene vertragliche oder gesetzliche Verpflichtungen zu erf\u00fcllen oder um Anordnungen von Beh\u00f6rden und\/oder Aufsichtsbeh\u00f6rden nachzukommen sowie um betr\u00fcgerische Aktivit\u00e4ten zu verhindern oder im Falle eines Rechtsstreits.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-10.png\" \/><\/div><div style=\"width: 92%;\"><p>M<strong>ETHODEN UND ART DER<\/strong> DATENBETEILIGUNG Die Daten werden rechtm\u00e4\u00dfig und nach Treu und Glauben f\u00fcr die oben genannten Zwecke in \u00dcbereinstimmung mit den Grunds\u00e4tzen und Anforderungen von Artikel 5 Absatz 1 der DSGVO erhoben und gespeichert. Die personenbezogenen Daten werden mit manuellen, computergest\u00fctzten und telematischen Mitteln mit einer Logik verarbeitet, die streng mit den Zwecken zusammenh\u00e4ngt, und in jedem Fall so, dass Sicherheit und Vertraulichkeit gew\u00e4hrleistet sind. Die Bereitstellung von Daten f\u00fcr die oben genannten Zwecke ist v\u00f6llig freiwillig.<br \/>Die Weigerung der betroffenen Person, personenbezogene Daten zu \u00fcbermitteln, das Fehlen der Zustimmung oder deren Widerruf f\u00fcr einen oder mehrere Zwecke hat zur Folge, dass die damit verbundenen Dienste nicht genutzt werden k\u00f6nnen. Die Nichtbereitstellung von Daten kann dazu f\u00fchren, dass die angeforderten Dienste nicht in Anspruch genommen werden k\u00f6nnen oder dass der Zugang zum LISCIANIGIOCHI APP Ecosystem und die vollst\u00e4ndige Nutzung des Ger\u00e4ts nicht m\u00f6glich sind.<\/p><hr \/><p>S<strong>ICHERHEITSMASSNAHMEN<\/strong> Die \u00dcbertragung, Speicherung und Verarbeitung der \u00fcber die Website erhobenen Daten der betroffenen Person wird durch geeignete technische und Sicherheitsma\u00dfnahmen gew\u00e4hrleistet. Einige der wichtigsten Sicherheitsma\u00dfnahmen sind die folgenden<\/p><p>&#8211; alle Informationen der betroffenen Person mit den vom Benutzer selbst gew\u00e4hlten Zugangsschl\u00fcsseln gesch\u00fctzt sind und Passw\u00f6rter nicht im Klartext aufgezeichnet werden; &#8211; die Website mit einer verschl\u00fcsselten HTTPS-Verbindung ausgestattet ist; &#8211; eine sichere E-Commerce-Plattform mit integrierten Sicherheitsprotokollen verwendet wird; &#8211; komplexe Passw\u00f6rter verwendet werden; &#8211; die Daten der betroffenen Person auf einem sicheren Server erfasst, gespeichert und gepflegt werden, der durch eine Firewall gesch\u00fctzt ist und sich physisch in einer zugangskontrollierten Webfarm in der EU befindet.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-11.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTE DER BETROFFENEN PARTEIEN<\/strong><\/p><p>In \u00dcbereinstimmung mit, innerhalb der Grenzen und unter den Bedingungen, die in den Datenschutzgesetzen \u00fcber die Aus\u00fcbung der Rechte der betroffenen Personen (Artikel 15 bis 22) festgelegt sind, k\u00f6nnen die Nutzer als betroffene Personen in Bezug auf die von dieser Mitteilung erfassten Verarbeitungen bestimmte Rechte in Bezug auf die vom f\u00fcr die Verarbeitung Verantwortlichen verarbeiteten Daten aus\u00fcben.<\/p><p>Die betroffene Person hat insbesondere das Recht auf:<\/p><p>&#8211; Jederzeitige R\u00fccknahme der Zustimmung<\/p><p>&#8211; Einspruch gegen die Verarbeitung der eigenen Daten<\/p><p>&#8211; Zugang zu den eigenen Daten<\/p><p>&#8211; \u00dcberpr\u00fcfung und Berichtigung<\/p><p>&#8211; Einschr\u00e4nkung der Behandlung<\/p><p>&#8211; L\u00f6schung oder Entfernung von pers\u00f6nlichen Daten<\/p><p>&#8211; Tragbarkeit<\/p><p>Dar\u00fcber hinaus hat die betroffene Person das Recht, bei der zust\u00e4ndigen Datenschutzaufsichtsbeh\u00f6rde eine Beschwerde einzureichen oder rechtliche Schritte einzuleiten, wenn sie der Ansicht ist, dass die sie betreffenden Verarbeitungen gegen die Bestimmungen der DSGVO versto\u00dfen, wie in Artikel 77 der DSGVO vorgesehen.<\/p><p><strong>Die betroffene Person kann eine erteilte Einwilligung jederzeit widerrufen.<\/strong><\/p><p><strong>Wie Sie Ihre Rechte aus\u00fcben<\/strong><\/p><p>Wenn Sie weitere Informationen \u00fcber die Verarbeitung Ihrer pers\u00f6nlichen Daten anfordern oder Ihre Rechte aus\u00fcben m\u00f6chten, kontaktieren Sie uns bitte schriftlich unter <a href=\"mailto:privacy@liscianigiochi.it\"><strong>privacy@liscianigiochi.it<\/strong><\/a> und verwenden Sie das<strong> &#8220;<\/strong><a href=\"https:\/\/d.docs.live.net\/9970872860be413a\/MG-FLO-LU\/S%5e0I%20CONSULTING%20TERAMO%2021.06.21\/LISCIANI%20GIOGHI%20SPA\/NUOVO%20SITO%20WEB\/BOZZA%20PRIVACY_COOKIE%20POLICY\/7.%20MODULO%20ESERCIZIO%20DIRITTI.docx\"><strong>Formular zur Aus\u00fcbung von Rechten<\/strong><\/a><strong>&#8220;.<\/strong> Die Antr\u00e4ge werden kostenlos eingereicht und vom f\u00fcr die Verarbeitung Verantwortlichen so schnell wie m\u00f6glich, in jedem Fall aber innerhalb eines Monats, bearbeitet.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-12.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>AUTOMATISIERTER PROZESS<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche f\u00fchrt in Bezug auf die nachstehend aufgef\u00fchrten Verarbeitungen unter keinen Umst\u00e4nden Verarbeitungen durch, die aus automatisierten Entscheidungsprozessen in Bezug auf die Daten nat\u00fcrlicher Personen bestehen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-13.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>\u00c4NDERUNGEN AN DIESER DATENSCHUTZRICHTLINIE<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche beh\u00e4lt sich das Recht vor, jederzeit \u00c4nderungen an dieser Datenschutzerkl\u00e4rung vorzunehmen, indem er die Nutzer per E-Mail und auf der Website dar\u00fcber informiert.<br \/>Der f\u00fcr die Verarbeitung Verantwortliche wird gegebenenfalls die Zustimmung der betroffenen Person erneut einholen. Letzte \u00c4nderung: 21\/06\/2024<\/p><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1353\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1353\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Informationen \u00fcber die Verarbeitung personenbezogener Daten Newsletter<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1353\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1353\"><p><strong>INFORMATIONEN \u00dcBER DIE VERARBEITUNG DER PERSONENBEZOGENEN DATEN VON NEWSLETTER-ABONNENTEN<\/strong><\/p><p><strong>gem\u00e4\u00df Art. 13 der Verordnung (EU) 2016\/679 <\/strong><\/p><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DATENVERANTWORTLICHER UND KONTAKTANGABEN<\/strong><\/p><p>L<strong>ISCIANI GIOCHI S.P.A. <\/strong>ist der Verantwortliche f\u00fcr die personenbezogenen Daten, die \u00fcber die Website www.liscianigiochi.com und innerhalb des LISCIANIGIOCHI App Ecosystems verarbeitet werden. Der Sitz befindet sich in Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te), P.IVA 00723030672.<strong><br \/>F\u00fcr alle Aspekte des Datenschutzes k\u00f6nnen Sie sich an die folgende E-Mail-Adresse wenden: <\/strong><strong>privacy@liscianigiochi.itovvero die Telefonnummer +39 0861 2311. Die institutionelle Website hat die folgende Adresse:<strong>https:<\/strong> \/\/www.liscianigroup.com <\/strong><\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-2.png\" \/><\/div><div style=\"width: 92%;\"><p>B<strong>ESCHREIBUNG DER VERARBEITUNG UND KATEGORIEN DER<\/strong> BETROFFENEN PERSONEN Die personenbezogenen Daten der Newsletter-Abonnenten werden \u00fcber das Newsletter-Abonnementformular erhoben. Die Verarbeitung erfolgt in voller \u00dcbereinstimmung mit den geltenden Gesetzen und garantiert die Sicherheit, die Vertraulichkeit und den Schutz der Daten, die sich in ihrem Besitz befinden, sowie die anerkannten Grundrechte und -freiheiten in \u00dcbereinstimmung mit den Bestimmungen der GDPR.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-3.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ARTEN DER ERHOBENEN DATEN UND HERKUNFT DER DATEN<\/strong><\/p><p>Bei den verarbeiteten personenbezogenen Daten handelt es sich um solche, die der Nutzer freiwillig durch das Ausf\u00fcllen von Online-Formularen und das Abonnieren des Newsletters angibt. Es wird nur das EMAIL der betreffenden Person erfasst.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-4.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ZWECK DER VERARBEITUNG<\/strong><\/p><p>1.<br \/>Newsletter-\/Direktmarketing-Aktivit\u00e4ten des f\u00fcr die Verarbeitung Verantwortlichen: Durch die Anmeldung zum Newsletter wird die E-Mail-Adresse der betroffenen Person automatisch in eine Mailingliste aufgenommen, an die in regelm\u00e4\u00dfigen Abst\u00e4nden E-Mails mit technischen, kommerziellen, werblichen und\/oder marketingbezogenen Informationen gesendet werden k\u00f6nnen. 2. Umfragen zur Kundenzufriedenheit: Personenbezogene Daten werden zum Zweck des Versands von Frageb\u00f6gen zur Kundenzufriedenheit per E-Mail verarbeitet.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-5.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTSGRUNDLAGE<\/strong><\/p><p>Rechtsgrundlage f\u00fcr die Verarbeitung ist die durch Erkl\u00e4rung zum Ausdruck gebrachte Einwilligung in die Zusendung von Newslettern und Zufriedenheitsfrageb\u00f6gen (Art. 6(1)(a) GDPR). Unter Bezugnahme auf Art. 7 der GDPR kann die betroffene Person eine erteilte Einwilligung jederzeit widerrufen. Der Widerruf der Einwilligung, der \u00fcber den entsprechenden Link in der Fu\u00dfzeile des E-Mail-Newsletters erfolgen kann, f\u00fchrt dazu, dass der Versand des Newsletters eingestellt wird. Ein Widerruf hat keinen Einfluss auf die Rechtm\u00e4\u00dfigkeit der vor dem Widerruf erfolgten Verarbeitung.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-7.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ADRESSATEN UND KATEGORIEN<\/strong><\/p><p>Die vom f\u00fcr die Verarbeitung Verantwortlichen verarbeiteten personenbezogenen Daten werden nicht weitergegeben.<br \/>Andererseits k\u00f6nnen sie an externe Personen, die als Datenverarbeiter bezeichnet werden (wie z.B. dritte technische Dienstleister, Hosting-Anbieter, IT-Unternehmen, Kommunikationsagenturen, Anbieter von Website-Verwaltungs- und Entwicklungsdiensten, Server- und Netzwerk-Support- und Wartungsdienste, Anbieter von Newsletter-Verwaltungsplattformen) oder an Personen, die zur Datenverarbeitung befugt sind, weil sie unter der Aufsicht des f\u00fcr die Verarbeitung Verantwortlichen t\u00e4tig sind, oder an andere Personen, die an der Organisation dieser Website beteiligt sind (Verwaltungs-, Vertriebs-, Marketing-, Rechts- und Systemadministratoren), \u00fcbermittelt werden.<br \/>Schlie\u00dflich k\u00f6nnen die Daten an Personen weitergegeben werden, die aufgrund von Gesetzen, Verordnungen oder EU-Rechtsvorschriften zum Zugriff auf sie berechtigt sind.<\/p><p>Zur Erf\u00fcllung gesetzlicher Verpflichtungen oder zur Feststellung der Verantwortlichkeit im Falle von Computerkriminalit\u00e4t zum Nachteil der Website k\u00f6nnen die Daten an Dritte weitergegeben oder ihnen zugeordnet werden. Die aktualisierte Liste der Datenverarbeiter kann jederzeit beim Inhaber der Datenverarbeitung angefordert werden. Insbesondere die Infrastruktur f\u00fcr die Verwaltung und den Versand von Newslettern ist Brevo Sas mit Sitz in 55 rue d&#8217;Amsterdam, 75008 Paris, Frankreich, anvertraut.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-8.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>\u00dcBERWEISUNG INS AUSLAND<\/strong><\/p><p>Die Daten werden in den R\u00e4umlichkeiten des f\u00fcr die Verarbeitung Verantwortlichen und an jedem anderen Ort, an dem sich die an der Verarbeitung beteiligten Parteien befinden, verarbeitet, so dass der f\u00fcr die Verarbeitung Verantwortliche diese personenbezogenen Daten nicht an Drittl\u00e4nder oder internationale Organisationen au\u00dferhalb der EU weitergibt. Er beh\u00e4lt sich jedoch das Recht vor, Cloud-Dienste zu nutzen. In diesem Fall werden die Dienstleister unter denjenigen ausgew\u00e4hlt, die angemessene Garantien bieten, wie in Artikel 46 GDPR vorgesehen. Die Verarbeitung von Informationen und Daten, die an diese Parteien weitergegeben werden k\u00f6nnen, erfordert ein gleichwertiges Schutzniveau, wie es f\u00fcr die Verarbeitung der personenbezogenen Daten seiner Mitarbeiter gilt. In jedem Fall werden nur die Daten \u00fcbermittelt, die f\u00fcr die Verfolgung der beabsichtigten Zwecke erforderlich sind, und es werden die vorgesehenen Regulierungsinstrumente angewandt.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-9.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DAUER DER BEHANDLUNG<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche speichert und verarbeitet personenbezogene Daten f\u00fcr den Zeitraum, der zur Erf\u00fcllung der angegebenen Zwecke erforderlich ist, d.h. f\u00fcr den Zeitraum, in dem der f\u00fcr die Verarbeitung Verantwortliche den Dienst aktiv h\u00e4lt, es sei denn, die betroffene Person widerruft ihre Einwilligung. In jeder Nachricht wird der Nutzer daran erinnert, dass er die M\u00f6glichkeit hat, den Dienst \u00fcber einen speziellen Link in der Fu\u00dfzeile jeder E-Mail abzubestellen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-10.png\" \/><\/div><div style=\"width: 92%;\"><p>M<strong>ETHODEN UND ART DER<\/strong> \u00dcBERMITTLUNG Die Datenerhebung und -speicherung erfolgt rechtm\u00e4\u00dfig und nach Treu und Glauben f\u00fcr die oben genannten Zwecke unter Einhaltung der Grunds\u00e4tze und Anforderungen von Artikel 5 Absatz 1 der DSGVO. Die Verarbeitung der personenbezogenen Daten erfolgt mit manuellen, computergest\u00fctzten und telematischen Mitteln mit einer Logik, die streng mit den Zwecken zusammenh\u00e4ngt, und in jedem Fall so, dass Sicherheit und Vertraulichkeit gew\u00e4hrleistet sind. Die Bereitstellung der Daten f\u00fcr die oben genannten Zwecke ist v\u00f6llig freiwillig. Die Weigerung der betroffenen Person, personenbezogene Daten zur Verf\u00fcgung zu stellen, die fehlende Einwilligung oder der Widerruf der Einwilligung f\u00fcr einen oder mehrere der oben genannten Zwecke hat zur Folge, dass die damit verbundenen Dienste nicht genutzt werden k\u00f6nnen oder dass der Newsletter nicht empfangen werden kann.<\/p><hr \/><p>S<strong>ICHERHEITSMASSNAHMEN<\/strong> Die \u00dcbertragung, Speicherung und Verarbeitung der \u00fcber die Website erhobenen Daten der betroffenen Person wird durch geeignete technische und Sicherheitsma\u00dfnahmen gew\u00e4hrleistet. Einige der wichtigsten Sicherheitsma\u00dfnahmen sind die folgenden<\/p><p>&#8211; alle Informationen der betroffenen Person mit den vom Benutzer gew\u00e4hlten Zugangsschl\u00fcsseln gesch\u00fctzt sind und Passw\u00f6rter nicht im Klartext aufgezeichnet werden; &#8211; die Website mit einer verschl\u00fcsselten HTTPS-Verbindung ausgestattet ist; &#8211; eine sichere E-Commerce-Plattform mit integrierten Sicherheitsprotokollen verwendet wird; &#8211; komplexe Passw\u00f6rter verwendet werden; &#8211; die Daten der betroffenen Person auf einem sicheren Server gesammelt, gespeichert und gepflegt werden, der durch eine Firewall gesch\u00fctzt ist und sich physisch in einer zugangskontrollierten Webfarm in der EU befindet.<\/p><\/div><\/div><hr \/><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-12.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>AUTOMATISIERTER PROZESS<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche f\u00fchrt in Bezug auf die nachstehend aufgef\u00fchrten Verarbeitungen unter keinen Umst\u00e4nden Verarbeitungen durch, die aus Entscheidungen auf der Grundlage automatisierter Verfahren \u00fcber die Daten von nat\u00fcrlichen Personen bestehen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-11.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTE DER BETROFFENEN PARTEIEN<\/strong><\/p><p>In \u00dcbereinstimmung mit, innerhalb der Grenzen und unter den Bedingungen, die in den Datenschutzgesetzen \u00fcber die Aus\u00fcbung der Rechte der betroffenen Personen (Artikel 15 bis 22) festgelegt sind, k\u00f6nnen die Nutzer als betroffene Personen in Bezug auf die von dieser Mitteilung erfassten Verarbeitungen bestimmte Rechte in Bezug auf die vom f\u00fcr die Verarbeitung Verantwortlichen verarbeiteten Daten aus\u00fcben.<\/p><p>Die betroffene Person hat insbesondere das Recht auf:<\/p><p>&#8211; Jederzeitige R\u00fccknahme der Zustimmung<\/p><p>&#8211; Einspruch gegen die Verarbeitung der eigenen Daten<\/p><p>&#8211; Zugang zu den eigenen Daten<\/p><p>&#8211; \u00dcberpr\u00fcfung und Berichtigung<\/p><p>&#8211; Einschr\u00e4nkung der Behandlung<\/p><p>&#8211; L\u00f6schung oder Entfernung von pers\u00f6nlichen Daten<\/p><p>&#8211; Tragbarkeit<\/p><p>Dar\u00fcber hinaus hat die betroffene Person das Recht, bei der zust\u00e4ndigen Datenschutzaufsichtsbeh\u00f6rde eine Beschwerde einzureichen oder rechtliche Schritte einzuleiten, wenn sie der Ansicht ist, dass die sie betreffenden Verarbeitungen gegen die Bestimmungen der DSGVO versto\u00dfen, wie in Artikel 77 der DSGVO vorgesehen.<\/p><p><strong>Die betroffene Person kann eine erteilte Einwilligung jederzeit widerrufen.<\/strong><\/p><p><strong>Wie Sie Ihre Rechte aus\u00fcben<\/strong><\/p><p>Wenn Sie weitere Informationen \u00fcber die Verarbeitung Ihrer pers\u00f6nlichen Daten anfordern oder Ihre Rechte aus\u00fcben m\u00f6chten, kontaktieren Sie uns bitte schriftlich unter <a href=\"mailto:privacy@liscianigiochi.it\"><strong>privacy@liscianigiochi.it<\/strong><\/a> und verwenden Sie das<strong> &#8220;<\/strong><a href=\"https:\/\/d.docs.live.net\/9970872860be413a\/MG-FLO-LU\/S%5e0I%20CONSULTING%20TERAMO%2021.06.21\/LISCIANI%20GIOGHI%20SPA\/NUOVO%20SITO%20WEB\/BOZZA%20PRIVACY_COOKIE%20POLICY\/7.%20MODULO%20ESERCIZIO%20DIRITTI.docx\"><strong>Formular zur Aus\u00fcbung von Rechten<\/strong><\/a><strong>&#8220;.<\/strong> Die Antr\u00e4ge werden kostenlos eingereicht und vom f\u00fcr die Verarbeitung Verantwortlichen so schnell wie m\u00f6glich, in jedem Fall aber innerhalb eines Monats, bearbeitet.<\/p><\/div><\/div><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-13.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>\u00c4NDERUNGEN AN DIESER DATENSCHUTZRICHTLINIE<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche beh\u00e4lt sich das Recht vor, jederzeit \u00c4nderungen an dieser Datenschutzerkl\u00e4rung vorzunehmen, indem er die Nutzer per E-Mail und auf der Website dar\u00fcber informiert.<br \/>Der f\u00fcr die Verarbeitung Verantwortliche wird gegebenenfalls die Zustimmung der betroffenen Person erneut einholen. Letzte \u00c4nderung: 21\/06\/2024<\/p><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1354\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1354\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Informationen \u00fcber die Verarbeitung von pers\u00f6nlichen Daten von Kunden und Lieferanten  <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1354\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1354\"><p><strong>INFORMATIONEN \u00dcBER DIE VERARBEITUNG DER PERS\u00d6NLICHEN DATEN VON KUNDEN UND LIEFERANTEN<\/strong><\/p><p><strong>gem\u00e4\u00df Art. 13 der Verordnung (EU) 2016\/679 <\/strong><\/p><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DATENVERANTWORTLICHER UND KONTAKTANGABEN<\/strong><\/p><p>L<strong>ISCIANI GIOCHI S.P.A. <\/strong>ist der Verantwortliche f\u00fcr die personenbezogenen Daten, die \u00fcber die Website www.liscianigiochi.com und innerhalb des LISCIANIGIOCHI App Ecosystems verarbeitet werden. Der Sitz befindet sich in Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te), P.IVA 00723030672.<strong><br \/>F\u00fcr alle Aspekte des Datenschutzes k\u00f6nnen Sie sich an die folgende E-Mail-Adresse wenden: <\/strong><strong>privacy@liscianigiochi.itovvero die Telefonnummer +39 0861 2311. Die institutionelle Website hat die folgende Adresse:<strong>https:<\/strong> \/\/www.liscianigroup.com <\/strong><\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-2.png\" \/><\/div><div style=\"width: 92%;\"><p>B<strong>ESCHREIBUNG DER VERARBEITUNG UND KATEGORIEN BETROFFENER PERSONEN<\/strong> Die Verarbeitung Ihrer personenbezogenen Daten in Ihrer Eigenschaft als potenzieller Kunde\/Lieferant und\/oder Kunde\/Lieferant von Waren und Dienstleistungen erfolgt unter Einhaltung der in Artikel 32 der Verordnung (EU) 2016\/679 festgelegten Sicherheitsma\u00dfnahmen. Die Verwaltung der vertraglichen Beziehungen mit Kunden\/Lieferanten (haupts\u00e4chlich juristische Personen) bringt zwangsl\u00e4ufig die Verarbeitung personenbezogener Daten (Identifizierung, Telefonnummern, E-Mail) der Personen mit sich, mit denen Sie in Kontakt treten. Dieses Informationsschreiben richtet sich daher an nat\u00fcrliche Personen, die mit Kunden\/Lieferanten zusammenarbeiten.<br \/>Da es schwierig ist, ihn direkt an die betroffenen Personen zu senden, wird der Informationshinweis auf der Website des f\u00fcr die Verarbeitung Verantwortlichen zur Verf\u00fcgung gestellt, mit der Bitte, die betroffenen Personen zu benachrichtigen. Die von der Verarbeitung betroffenen Personen sind die nat\u00fcrlichen Personen, die als Angestellte oder aufgrund einer anderen Art von Beziehung zu den juristischen Personen Kunden\/Lieferanten operativ in die kommerzielle, vorvertragliche und vertragliche Kommunikation eingebunden sind. Dar\u00fcber hinaus k\u00f6nnen auch Kunden\/Lieferanten, die nat\u00fcrliche Personen, Berater, Freiberufler oder Einzelunternehmer sind, verarbeitet werden.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-3.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ARTEN VON VERARBEITETEN DATEN<\/strong><\/p><p>Bei den verarbeiteten personenbezogenen Daten handelt es sich um Identifikationsdaten (z.B. Vorname, Nachname, Firmenname, Adresse, Telefon, E-Mail, Bank- und Zahlungsreferenzen).<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-4.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ZWECK DER VERARBEITUNG<\/strong><\/p><p>Die Daten werden f\u00fcr die Verwaltung von Kunden und Lieferanten verarbeitet, und zwar f\u00fcr: 1. den Abschluss von Vertr\u00e4gen \u00fcber die Dienstleistungen\/Produkte des f\u00fcr die Verarbeitung Verantwortlichen oder des Lieferanten; die Erf\u00fcllung vorvertraglicher, vertraglicher und steuerlicher Verpflichtungen, die sich aus bestehenden Beziehungen ergeben; 2. die Erf\u00fcllung gesetzlich vorgeschriebener Verpflichtungen; 3. die Aus\u00fcbung der Rechte des f\u00fcr die Verarbeitung Verantwortlichen, wie das Recht auf Verteidigung vor Gericht und die Verwaltung von Rechtsstreitigkeiten; 4. kommerzielle Kommunikation und Marketing.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-5.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTSGRUNDLAGE<\/strong><\/p><p>&#8211; F\u00fcr die unter Punkt 1 genannten Zwecke: Die Verarbeitung ist f\u00fcr die Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, oder f\u00fcr die Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, die auf Antrag der betroffenen Person erfolgen (Art. 6(1)(b) GDPR).<br \/>&#8211; F\u00fcr den unter Punkt 2 genannten Zweck: Die Verarbeitung ist f\u00fcr die Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich, der der f\u00fcr die Datenverarbeitung Verantwortliche unterliegt. (Art. 6 Abs. 1 Buchst. c) der DSGVO). <br \/>&#8211; F\u00fcr den unter Punkt 3 genannten Zweck: Die Verarbeitung ist zur Verfolgung der berechtigten Interessen des f\u00fcr die Verarbeitung Verantwortlichen oder Dritter erforderlich (Art. 6(1)(f) GDPR).<br \/>&#8211; F\u00fcr die Zwecke von Punkt 4: Zustimmung der betroffenen Person.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-7.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ADRESSATEN UND KATEGORIEN<\/strong><\/p><p>Die vom f\u00fcr die Verarbeitung Verantwortlichen verarbeiteten personenbezogenen Daten werden nicht offengelegt, d.h. sie werden nicht an nicht n\u00e4her bezeichnete Personen weitergegeben, und zwar in keiner Form, auch nicht durch Zurverf\u00fcgungstellung oder einfache Einsichtnahme.<br \/>Sie k\u00f6nnen jedoch an Mitarbeiter des f\u00fcr die Datenverarbeitung Verantwortlichen, an externe Personen, die mit dem f\u00fcr die Datenverarbeitung Verantwortlichen zusammenarbeiten, die als Datenverarbeiter bezeichnet werden oder zur Datenverarbeitung befugt sind, da sie unter der Autorit\u00e4t des f\u00fcr die Datenverarbeitung Verantwortlichen t\u00e4tig sind, sowie, soweit unbedingt erforderlich, an Personen, die im Rahmen der Bearbeitung Ihrer Anfragen Waren liefern oder Dienstleistungen im Auftrag des f\u00fcr die Datenverarbeitung Verantwortlichen erbringen m\u00fcssen, weitergegeben werden. Schlie\u00dflich k\u00f6nnen sie an Personen weitergegeben werden, die aufgrund von Gesetzen, Verordnungen oder EU-Rechtsvorschriften zum Zugriff auf diese Daten berechtigt sind, wie z.B.: Kreditinstitute, Spediteure, unsere Buchhalter und Anw\u00e4lte, Hardware- und Software-Wartungsfirmen. <br \/>Insbesondere sind die Mitarbeiter aufgrund ihrer Rolle und ihrer Arbeitsaufgaben befugt, Ihre personenbezogenen Daten im Rahmen ihrer Zust\u00e4ndigkeiten und gem\u00e4\u00df den Anweisungen des f\u00fcr die Verarbeitung Verantwortlichen zu verarbeiten.<br \/>Die aktualisierte Liste der Datenverarbeiter kann jederzeit beim Data Controller angefordert werden.<br \/>Dies gilt unbeschadet der Verpflichtung von LISCIANI GIOCHI S.P.A., die Daten auf besondere Anfrage an Beh\u00f6rden weiterzugeben.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-8.png\" \/><\/div><div style=\"width: 92%;\"><p>Die Verarbeitung der Daten erfolgt in den Betriebsb\u00fcros des f\u00fcr die Verarbeitung Verantwortlichen und an jedem anderen Ort, an dem sich die an der Verarbeitung beteiligten Parteien befinden, daher \u00fcbermittelt der f\u00fcr die Verarbeitung Verantwortliche diese personenbezogenen Daten nicht an Drittl\u00e4nder oder internationale Organisationen. Der f\u00fcr die Verarbeitung Verantwortliche beh\u00e4lt sich jedoch das Recht vor, Cloud-Dienste in Anspruch zu nehmen; in diesem Fall werden die Dienstleister unter denjenigen ausgew\u00e4hlt, die angemessene Garantien bieten, wie in Artikel 46 GDPR vorgesehen. Die Verarbeitung der Informationen und Daten, die an diese Parteien weitergegeben werden k\u00f6nnen, erfordert ein gleichwertiges Schutzniveau wie die Verarbeitung der personenbezogenen Daten der Mitarbeiter des Unternehmens. In jedem Fall werden nur die Daten \u00fcbermittelt, die f\u00fcr die Verfolgung der beabsichtigten Zwecke erforderlich sind, und es werden die in Kapitel V der DSGVO vorgesehenen Regulierungsinstrumente angewandt.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-9.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DAUER DER BEHANDLUNG<\/strong><\/p><p>Die f\u00fcr die oben genannten Zwecke erhobenen Daten werden f\u00fcr die gesamte Dauer des Vertrags und nach Beendigung des Vertrags f\u00fcr 10 Jahre aufbewahrt. Im Falle eines Rechtsstreits werden die Daten f\u00fcr die gesamte Dauer des Rechtsstreits aufbewahrt, bis die Frist f\u00fcr Rechtsmittel ausgesch\u00f6pft ist.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-10.png\" \/><\/div><div style=\"width: 92%;\"><p>M<strong>ETHODEN UND ART DER<\/strong> DATENVERARBEITUNG Ihre Daten werden rechtm\u00e4\u00dfig und nach Treu und Glauben f\u00fcr die oben genannten Zwecke in \u00dcbereinstimmung mit den Grunds\u00e4tzen und Vorschriften von Artikel 5 Absatz 1 der DSGVO erhoben und gespeichert. Die personenbezogenen Daten werden mit manuellen, computergest\u00fctzten und telematischen Mitteln mit einer Logik verarbeitet, die streng mit den Zwecken zusammenh\u00e4ngt, und in jedem Fall so, dass Sicherheit und Vertraulichkeit gew\u00e4hrleistet sind.<\/p><p>Ihre Zustimmung ist f\u00fcr die Daten, die f\u00fcr die Anforderungen im Zusammenhang mit den oben genannten Zwecken erhoben und verwendet werden, nicht erforderlich. Die \u00dcbermittlung der personenbezogenen Daten f\u00fcr die in dieser Erkl\u00e4rung genannten Zwecke und ihre Verarbeitung sind f\u00fcr den Abschluss und die Ausf\u00fchrung des Vertrags erforderlich, so dass die Nicht\u00fcbermittlung oder unvollst\u00e4ndige \u00dcbermittlung derselben die Unm\u00f6glichkeit der Fortsetzung der betreffenden Beziehung zur Folge hat.<\/p><\/div><\/div><hr \/><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-11.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTE DER BETROFFENEN PARTEIEN<\/strong><\/p><p>In \u00dcbereinstimmung mit, innerhalb der Grenzen und unter den Bedingungen, die in den Datenschutzgesetzen \u00fcber die Aus\u00fcbung der Rechte der betroffenen Personen (Artikel 15 bis 22) festgelegt sind, k\u00f6nnen die Nutzer als betroffene Personen in Bezug auf die in diesem Informationsschreiben genannten Verarbeitungen bestimmte Rechte in Bezug auf die vom f\u00fcr die Verarbeitung Verantwortlichen verarbeiteten Daten aus\u00fcben.<\/p><p>Die betroffene Person hat insbesondere das Recht auf:<\/p><p>&#8211; Jederzeitige R\u00fccknahme der Zustimmung<\/p><p>&#8211; Einspruch gegen die Verarbeitung der eigenen Daten<\/p><p>&#8211; Zugang zu den eigenen Daten<\/p><p>&#8211; Verifizierung und Berichtigung<\/p><p>&#8211; Einschr\u00e4nkung der Behandlung<\/p><p>&#8211; L\u00f6schung oder Entfernung von pers\u00f6nlichen Daten<\/p><p>&#8211; Tragbarkeit<\/p><p>Dar\u00fcber hinaus hat die betroffene Person das Recht, bei der zust\u00e4ndigen Datenschutzaufsichtsbeh\u00f6rde eine Beschwerde einzureichen oder rechtliche Schritte einzuleiten, wenn sie der Ansicht ist, dass die sie betreffenden Verarbeitungen gegen die Bestimmungen der DSGVO versto\u00dfen, wie in Artikel 77 der DSGVO vorgesehen.<\/p><p><strong>Die betroffene Person kann eine erteilte Einwilligung jederzeit widerrufen.<\/strong><\/p><p><strong>Wie Sie Ihre Rechte aus\u00fcben<\/strong><\/p><p>Wenn Sie weitere Informationen \u00fcber die Verarbeitung Ihrer pers\u00f6nlichen Daten anfordern oder Ihre Rechte aus\u00fcben m\u00f6chten, kontaktieren Sie uns bitte schriftlich unter <a href=\"mailto:privacy@liscianigiochi.it\"><strong>privacy@liscianigiochi.it<\/strong><\/a> und verwenden Sie das<strong> &#8220;<\/strong><a href=\"https:\/\/d.docs.live.net\/9970872860be413a\/MG-FLO-LU\/S%5e0I%20CONSULTING%20TERAMO%2021.06.21\/LISCIANI%20GIOGHI%20SPA\/NUOVO%20SITO%20WEB\/BOZZA%20PRIVACY_COOKIE%20POLICY\/7.%20MODULO%20ESERCIZIO%20DIRITTI.docx\"><strong>Formular zur Aus\u00fcbung von Rechten<\/strong><\/a><strong>&#8220;.<\/strong> Die Antr\u00e4ge werden kostenlos eingereicht und vom f\u00fcr die Verarbeitung Verantwortlichen so schnell wie m\u00f6glich, in jedem Fall aber innerhalb eines Monats, bearbeitet.<\/p><\/div><\/div><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-12.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>AUTOMATISIERTER PROZESS<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche f\u00fchrt in Bezug auf die nachstehend aufgef\u00fchrten Verarbeitungen unter keinen Umst\u00e4nden Verarbeitungen durch, die aus Entscheidungen auf der Grundlage automatisierter Verfahren \u00fcber die Daten nat\u00fcrlicher Personen bestehen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-13.png\" \/><\/div><div style=\"width: 92%;\">\u00c4NDERUNGEN AN DIESER DATENSCHUTZPOLITIK <strong> Der f\u00fcr die Verarbeitung Verantwortliche beh\u00e4lt sich das Recht vor, jederzeit \u00c4nderungen an dieser Datenschutzerkl\u00e4rung vorzunehmen, indem er die Nutzer per E-Mail und auf der Website dar\u00fcber informiert.<br \/>Der f\u00fcr die Datenverarbeitung Verantwortliche wird gegebenenfalls die Zustimmung der betroffenen Person erneut einholen. Letzte \u00c4nderung: 09\/12\/2021<\/strong><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1355\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1355\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Informationen \u00fcber die Verarbeitung der pers\u00f6nlichen Daten der Bewerber<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1355\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1355\"><p><strong>INFORMATIONEN \u00dcBER DIE VERARBEITUNG DER PERS\u00d6NLICHEN DATEN DER BEWERBER<\/strong><\/p><p><strong>gem\u00e4\u00df Art. 13 der Verordnung (EU) 2016\/679 <\/strong><\/p><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DATENVERANTWORTLICHER UND KONTAKTANGABEN<\/strong><\/p><p>L<strong>ISCIANI GIOCHI S.P.A. <\/strong>ist der Verantwortliche f\u00fcr die personenbezogenen Daten, die \u00fcber die Website www.liscianigiochi.com und innerhalb des LISCIANIGIOCHI App Ecosystems verarbeitet werden. Der Sitz befindet sich in Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te), P.IVA 00723030672.<strong><br \/>F\u00fcr alle Aspekte des Datenschutzes k\u00f6nnen Sie sich an die folgende E-Mail-Adresse wenden: <\/strong><strong>privacy@liscianigiochi.itovvero die Telefonnummer +39 0861 2311. Die institutionelle Website hat die folgende Adresse:<strong>https:<\/strong> \/\/www.liscianigroup.com <\/strong><\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-2.png\" \/><\/div><div style=\"width: 92%;\"><p>B<strong>ESCHREIBUNG DER VERARBEITUNG UND KATEGORIEN DER BETROFFENEN PARTEIEN<\/strong> LISCIANI GIOCHI S.P.A. informiert Sie dar\u00fcber, dass Ihre personenbezogenen Daten f\u00fcr die Vorauswahl und die Auswahl von Mitarbeitern durch die Analyse von Lebensl\u00e4ufen und kognitive Interviews verarbeitet werden k\u00f6nnen. Bei den von der Verarbeitung betroffenen Personen handelt es sich insbesondere um nat\u00fcrliche Personen, die ihre Lebensl\u00e4ufe entweder spontan einreichen oder sich auf offene Stellen bewerben.<br \/>Die Erfassung erfolgt durch spontane Einsendung des Lebenslaufs, \u00fcber eine Website oder \u00fcber Personalagenturen. Die Bewerber werden gebeten, in ihren Lebensl\u00e4ufen keine besonderen oder gerichtlichen Daten aufzunehmen, die nicht unbedingt erforderlich sind, da sie sonst nicht verarbeitet werden k\u00f6nnen. Spontan \u00fcbermittelte Lebensl\u00e4ufe werden, wenn sie als uninteressant erachtet werden, vernichtet und nicht gespeichert; andernfalls wird der Bewerber umgehend kontaktiert, um ihn zu bitten, den Lebenslauf auf einem elektronischen Datentr\u00e4ger oder in Papierform aufzubewahren, und er erh\u00e4lt auch diesen Informationshinweis.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-3.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ARTEN DER VERARBEITETEN DATEN UND HERKUNFT DER DATEN<\/strong><\/p><p>Verarbeitete pers\u00f6nliche Daten:<br \/>Name, Adresse oder andere pers\u00f6nliche Identifikationsmerkmale, erkl\u00e4rter Beruf, berufliche Qualit\u00e4tszertifikate, Steuernummer und andere pers\u00f6nliche Identifikationsnummern, Foto, Wohnanschrift, E-Mail-Adresse, Bildung und Kultur, Beruf (derzeitiger, fr\u00fcherer Beruf, Lebenslauf usw.), Die Daten werden teilweise bei der betroffenen Person und teilweise bei Dritten erhoben.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-4.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ZWECK DER VERARBEITUNG<\/strong><\/p><p>1. Verwaltung der Bewertung Ihres Lebenslaufs; 2. Planung und Verwaltung von Auswahlgespr\u00e4chen, auch im interaktiven Modus oder in Gruppen; 3.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-5.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTSGRUNDLAGE<\/strong><\/p><p>F\u00fcr die Zwecke 1, 2, 3: Die Verarbeitung ist f\u00fcr die Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, oder f\u00fcr die Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, die auf Antrag der betroffenen Person erfolgen. F\u00fcr den Fall, dass der Bewerber in seinem Lebenslauf freiwillig angibt, dass er einer gesch\u00fctzten Kategorie angeh\u00f6rt, ist die Voraussetzung f\u00fcr die Verarbeitung solcher Daten &#8220;besonderer&#8221; Art, wenn \u00fcberhaupt, dass die Daten direkt von der betroffenen Person bereitgestellt werden. Ihre Verarbeitung k\u00f6nnte zur Erf\u00fcllung der Pflichten und zur Aus\u00fcbung der spezifischen Rechte des f\u00fcr die Datenverarbeitung Verantwortlichen oder der betroffenen Person im Bereich des Arbeitsrechts und der sozialen Sicherheit und des sozialen Schutzes erfolgen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-7.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>ADRESSATEN UND KATEGORIEN<\/strong><\/p><p>Die vom Inhaber der Datenverarbeitung verarbeiteten personenbezogenen Daten werden nicht weitergegeben. Sie k\u00f6nnen jedoch an Mitarbeiter des Inhabers der Datenverarbeitung und an externe Parteien weitergegeben werden, die mit dem Inhaber der Datenverarbeitung zusammenarbeiten und die als Datenverarbeiter benannt oder zur Verarbeitung der Daten befugt sind, da sie unter der Autorit\u00e4t des Inhabers der Datenverarbeitung t\u00e4tig sind. Alle Angestellten, Berater, Zeitarbeiter und\/oder andere Personen, die ihre T\u00e4tigkeit auf der Grundlage der von LISCIANI GIOCHI S.P.A. erhaltenen Anweisungen aus\u00fcben, werden gem\u00e4\u00df Art. 29 der DSGVO als &#8220;autorisierte Verarbeiter&#8221; bezeichnet.<br \/>Diesen gibt LISCIANI GIOCHI S.P.A. entsprechende Anweisungen, insbesondere in Bezug auf die Annahme und Einhaltung von Sicherheitsma\u00dfnahmen, um die Vertraulichkeit und Sicherheit der Daten zu gew\u00e4hrleisten. Die Daten k\u00f6nnen an Unternehmen und Fachleute weitergegeben werden, die von LISCIANI GIOCHI S.<\/p><p>P.A. beauftragten Datenverarbeiter \u00fcbermittelt werden, oder sie sind selbst die Inhaber der ihnen \u00fcbermittelten personenbezogenen Daten. Die aktualisierte Liste der Inhaber der Datenverarbeitung kann jederzeit beim Inhaber der Datenverarbeitung angefordert werden. Die Verpflichtung von LISCIANI GIOCHI S.P.A., die Daten auf besondere Anfrage an Beh\u00f6rden weiterzugeben, bleibt hiervon unber\u00fchrt.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-8.png\" \/><\/div><div style=\"width: 92%;\"><p>Die Verarbeitung der Daten erfolgt in den Gesch\u00e4ftsr\u00e4umen des f\u00fcr die Verarbeitung Verantwortlichen und an jedem anderen Ort, an dem sich die an der Verarbeitung beteiligten Parteien befinden. Der f\u00fcr die Verarbeitung Verantwortliche \u00fcbermittelt diese personenbezogenen Daten daher nicht an Drittl\u00e4nder oder internationale Organisationen. Er beh\u00e4lt sich jedoch das Recht vor, Cloud-Dienste in Anspruch zu nehmen; in diesem Fall werden die Dienstleister unter denjenigen ausgew\u00e4hlt, die angemessene Garantien bieten, wie in Artikel 46 GDPR vorgesehen. Die Verarbeitung von Informationen und Daten, die an diese Parteien weitergegeben werden k\u00f6nnen, erfordert ein gleichwertiges Schutzniveau, wie es f\u00fcr die Verarbeitung der personenbezogenen Daten seiner Mitarbeiter gilt. In jedem Fall werden nur die Daten \u00fcbermittelt, die f\u00fcr die Verfolgung der beabsichtigten Zwecke erforderlich sind, und es werden die in Kapitel V der DSGVO vorgesehenen Regulierungsinstrumente angewandt.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-9.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>DAUER DER BEHANDLUNG<\/strong><\/p><p>Die Verarbeitung dauert nicht l\u00e4nger, als es f\u00fcr die Zwecke, f\u00fcr die die Daten erhoben wurden, erforderlich ist, und wird f\u00fcr maximal 24 Monate ab dem Zeitpunkt der Bereitstellung der Daten aufbewahrt.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-10.png\" \/><\/div><div style=\"width: 92%;\"><p>M<strong>ETHODEN UND ART DER DATENVERARBEITUNG<\/strong> Ihre Daten werden rechtm\u00e4\u00dfig und nach Treu und Glauben f\u00fcr die oben genannten Zwecke in \u00dcbereinstimmung mit den Grunds\u00e4tzen und Vorschriften von Artikel 5 c 1 der DSGVO erhoben und gespeichert.<\/p><p>Die Verarbeitung der personenbezogenen Daten erfolgt mit manuellen, computergest\u00fctzten und telematischen Instrumenten mit einer streng auf die Zwecke bezogenen Logik und in jedem Fall so, dass Sicherheit und Vertraulichkeit gew\u00e4hrleistet sind. Ihre Zustimmung ist nicht erforderlich f\u00fcr die Daten, die f\u00fcr die Erfordernisse im Zusammenhang mit der Durchf\u00fchrung von Aktivit\u00e4ten im Rahmen der vertraglichen Beziehung und der Einhaltung der angegebenen gesetzlichen Verpflichtungen erhoben und verwendet werden. Die Nichtbereitstellung der oben genannten personenbezogenen Daten hat zur Folge, dass die betreffende Beziehung nicht durchgef\u00fchrt werden kann. F\u00fcr Daten, die aus dem berechtigten Interesse des f\u00fcr die Verarbeitung Verantwortlichen erhoben und verwendet werden, ist Ihre Zustimmung nicht erforderlich (Buchstabe f, Art. 6, GDPR). Die \u00dcbermittlung der oben genannten personenbezogenen Daten ist fakultativ, aber f\u00fcr die Erbringung der vom f\u00fcr die Verarbeitung Verantwortlichen angebotenen Dienstleistungen erforderlich. Eine Verweigerung der Mitteilung dieser Daten macht es unm\u00f6glich, die angeforderten Dienstleistungen ganz oder teilweise zu erbringen.<\/p><p>S<strong>ICHERHEITSMASSNAHMEN<\/strong> Die \u00dcbertragung, Speicherung und Verarbeitung der \u00fcber die Website gesammelten Daten der betroffenen Person wird durch geeignete technische und sicherheitstechnische Ma\u00dfnahmen gew\u00e4hrleistet, insbesondere: Alle Informationen der betroffenen Person werden mit den vom Benutzer selbst gew\u00e4hlten Zugangsschl\u00fcsseln gesch\u00fctzt, Passw\u00f6rter werden nicht im Klartext aufgezeichnet.<br \/>Die Website verf\u00fcgt \u00fcber eine verschl\u00fcsselte HTTPS-Verbindung.<br \/>Es wird eine sichere E-Commerce-Plattform mit integrierten Sicherheitsprotokollen verwendet.<br \/>Es werden komplexe Passw\u00f6rter verwendet.<br \/>Die Daten der betroffenen Personen werden auf einem sicheren Server erfasst, gespeichert und gepflegt, der durch eine Firewall gesch\u00fctzt ist und sich physisch in einer zugangskontrollierten Webfarm in der EU befindet.<\/p><\/div><\/div><hr \/><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-11.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>RECHTE DER BETROFFENEN PARTEIEN<\/strong><\/p><p>In \u00dcbereinstimmung mit, innerhalb der Grenzen und unter den Bedingungen, die in den Datenschutzgesetzen \u00fcber die Aus\u00fcbung der Rechte der betroffenen Personen (Artikel 15 bis 22) festgelegt sind, k\u00f6nnen die Nutzer als betroffene Personen in Bezug auf die von dieser Mitteilung erfassten Verarbeitungen bestimmte Rechte in Bezug auf die vom f\u00fcr die Verarbeitung Verantwortlichen verarbeiteten Daten aus\u00fcben.<\/p><p>Die betroffene Person hat insbesondere das Recht auf:<\/p><p>&#8211; Jederzeitige R\u00fccknahme der Zustimmung<\/p><p>&#8211; Einspruch gegen die Verarbeitung der eigenen Daten<\/p><p>&#8211; Zugang zu den eigenen Daten<\/p><p>&#8211; Verifizierung und Berichtigung<\/p><p>&#8211; Einschr\u00e4nkung der Behandlung<\/p><p>&#8211; L\u00f6schung oder Entfernung von pers\u00f6nlichen Daten<\/p><p>&#8211; Tragbarkeit<\/p><p>Dar\u00fcber hinaus hat die betroffene Person das Recht, bei der zust\u00e4ndigen Datenschutzaufsichtsbeh\u00f6rde eine Beschwerde einzureichen oder rechtliche Schritte einzuleiten, wenn sie der Ansicht ist, dass die sie betreffenden Verarbeitungen gegen die Bestimmungen der DSGVO versto\u00dfen, wie in Artikel 77 der DSGVO vorgesehen.<\/p><p><strong>Die betroffene Person kann eine erteilte Einwilligung jederzeit widerrufen.<\/strong><\/p><p><strong>Wie Sie Ihre Rechte aus\u00fcben k\u00f6nnen<\/strong><\/p><p>Wenn Sie weitere Informationen \u00fcber die Verarbeitung Ihrer pers\u00f6nlichen Daten anfordern oder Ihre Rechte aus\u00fcben m\u00f6chten, kontaktieren Sie uns bitte schriftlich unter <a href=\"mailto:privacy@liscianigiochi.it\"><strong>privacy@liscianigiochi.it<\/strong><\/a> und verwenden Sie das<strong> &#8220;<\/strong><a href=\"https:\/\/d.docs.live.net\/9970872860be413a\/MG-FLO-LU\/S%5e0I%20CONSULTING%20TERAMO%2021.06.21\/LISCIANI%20GIOGHI%20SPA\/NUOVO%20SITO%20WEB\/BOZZA%20PRIVACY_COOKIE%20POLICY\/7.%20MODULO%20ESERCIZIO%20DIRITTI.docx\"><strong>Formular zur Aus\u00fcbung von Rechten<\/strong><\/a><strong>&#8220;.<\/strong> Die Antr\u00e4ge werden kostenlos eingereicht und vom f\u00fcr die Verarbeitung Verantwortlichen so schnell wie m\u00f6glich, in jedem Fall aber innerhalb eines Monats, bearbeitet.<\/p><\/div><\/div><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-12.png\" \/><\/div><div style=\"width: 92%;\"><p><strong>AUTOMATISIERTER PROZESS<\/strong><\/p><p>Der f\u00fcr die Verarbeitung Verantwortliche f\u00fchrt in Bezug auf die nachstehend aufgef\u00fchrten Verarbeitungen unter keinen Umst\u00e4nden Verarbeitungen durch, die aus Entscheidungen auf der Grundlage automatisierter Verfahren \u00fcber die Daten von nat\u00fcrlichen Personen bestehen.<\/p><\/div><\/div><hr \/><div style=\"display: flex; justify-content: space-between;\"><div style=\"width: 8%;\"><img decoding=\"async\" src=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-13.png\" \/><\/div><div style=\"width: 92%;\">\u00c4NDERUNGEN AN DIESER DATENSCHUTZPOLITIK <strong> Der f\u00fcr die Verarbeitung Verantwortliche beh\u00e4lt sich das Recht vor, jederzeit \u00c4nderungen an dieser Datenschutzerkl\u00e4rung vorzunehmen, indem er die Nutzer per E-Mail und auf der Website dar\u00fcber informiert.<br \/>Der f\u00fcr die Verarbeitung Verantwortliche wird gegebenenfalls die Zustimmung der betroffenen Person erneut einholen. Letzte \u00c4nderung: 09\/12\/2021<\/strong><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1356\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1356\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Aus\u00fcbung der Rechte<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1356\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1356\"><p>Klicken Sie <a href=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/7.-MODULO-ESERCIZIO-DIRITTI.docx\">hier<\/a>, um das Formular zur Aus\u00fcbung Ihrer Datenschutzrechte herunterzuladen<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1357\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1357\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Definitionen<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1357\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1357\"><p>DEFINITIONEN<\/p><p>Definitionen und rechtliche Hinweise f\u00fcr die Datenschutzrichtlinie und die Cookie-Richtlinie von https:\/\/www.liscianigroup.com<\/p><p>Personenbezogene Daten (oder Daten): Personenbezogene Daten sind alle Informationen, die direkt oder indirekt, auch in Verbindung mit anderen Informationen, einschlie\u00dflich einer pers\u00f6nlichen Identifikationsnummer, eine nat\u00fcrliche Person identifizierbar oder identifizierbar machen.<br \/>Nutzungsdaten: Dies sind die Informationen, die automatisch \u00fcber diese Website (einschlie\u00dflich der in diese Website integrierten Anwendungen Dritter) erfasst werden, einschlie\u00dflich: IP-Adressen oder Dom\u00e4nennamen der Computer, die von der betroffenen Person f\u00fcr die Verbindung mit dieser Website verwendet werden, URI (Uniform Resource Identifier)-Notationsadressen, die Uhrzeit der Anfrage, die f\u00fcr die Weiterleitung der Anfrage an den Server verwendete Methode, die Gr\u00f6\u00dfe der als Antwort erhaltenen Datei, der Zahlencode, der den Status der Serverantwort angibt (erfolgreich, Fehler usw.), das Herkunftsland, die Merkmale des vom Besucher verwendeten Browsers und Betriebssystems, die verschiedenen zeitlichen Konnotationen des Besuchs (z. B. die auf jeder Seite verbrachte Zeit) und die Einzelheiten der vom Besucher verfolgten Reiseroute.) das Herkunftsland, die Merkmale des vom Besucher verwendeten Browsers und Betriebssystems, die verschiedenen zeitlichen Aspekte des Besuchs (z.B. die auf jeder Seite verbrachte Zeit) und die Einzelheiten der Reiseroute innerhalb der Anwendung, insbesondere die Reihenfolge der aufgerufenen Seiten, die Parameter des Betriebssystems und die IT-Umgebung der betroffenen Person.<br \/>Nutzer: die Person, die diese Website nutzt, die, sofern nicht anders angegeben, mit der betroffenen Person \u00fcbereinstimmt.<br \/>Betroffene Person: die nat\u00fcrliche Person, auf die sich die pers\u00f6nlichen Daten beziehen.<br \/>Datenverarbeiter (oder Controller): die nat\u00fcrliche Person, die juristische Person, die \u00f6ffentliche Verwaltung und jede andere Stelle, die personenbezogene Daten im Auftrag des Controllers verarbeitet, wie in dieser Datenschutzrichtlinie dargelegt.<br \/>Datenverantwortlicher (oder Controller): die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Dienststelle oder sonstige Einrichtung, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung personenbezogener Daten sowie \u00fcber die eingesetzten Instrumente, einschlie\u00dflich der Sicherheitsma\u00dfnahmen im Zusammenhang mit dem Betrieb und der Nutzung dieser Website, entscheidet. Der Datenverantwortliche ist, sofern nicht anders angegeben, der Eigent\u00fcmer dieser Website. <br \/>Diese Website (oder diese Anwendung): das Hardware- oder Software-Tool, \u00fcber das die pers\u00f6nlichen Daten der Nutzer gesammelt und verarbeitet werden.<br \/>Service: der von dieser Website angebotene Service, wie in den entsprechenden Bedingungen (falls vorhanden) auf dieser Website\/Anwendung definiert.<br \/>Europ\u00e4ische Union (oder EU): Sofern nicht anders angegeben, gilt jede Bezugnahme auf die Europ\u00e4ische Union in diesem Dokument als Bezugnahme auf alle derzeitigen Mitgliedstaaten der Europ\u00e4ischen Union und des Europ\u00e4ischen Wirtschaftsraums.<br \/>Cookie: ein kleiner Teil der Daten, der auf dem Ger\u00e4t der betroffenen Person gespeichert wird.<\/p><p>Rechtliche Hinweise Diese Datenschutzerkl\u00e4rung wurde auf der Grundlage mehrerer gesetzlicher Bestimmungen erstellt, darunter Artikel 13 und 14 der Verordnung (EU) 2016\/679.<br \/>Sofern nicht anders angegeben, bezieht sich diese Datenschutzrichtlinie ausschlie\u00dflich auf diese Website.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a8bf3f0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"a8bf3f0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d92cf79 elementor-widget elementor-widget-html\" data-id=\"d92cf79\" data-element_type=\"widget\" id=\"test-banner\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"CookieDeclaration\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informationen \u00fcber die Verarbeitung personenbezogener Daten Warum dieses Dokument LISCIANIGIOCHI S.P.A. (im Folgenden auch LISCIANIGIOCHI, &#8220;Unternehmen&#8221; oder &#8220;Eigent\u00fcmer&#8221;) setzt sich f\u00fcr die Achtung und den Schutz der Privatsph\u00e4re ein und m\u00f6chte eine klare und transparente Vorstellung davon vermitteln, welche Informationen \u00fcber Einzelpersonen gesammelt und verarbeitet werden: Kunden und Benutzer, die auf der Website surfen, Eink\u00e4ufe t\u00e4tigen, den Newsletter abonnieren oder LISCIANIGIOCHI um Unterst\u00fctzung bitten. Nach der vollst\u00e4ndigen Umsetzung der Allgemeinen Datenschutzverordnung 2016\/679 (die sogenannte &#8220;GDPR&#8221; oder &#8220;Verordnung&#8221;) in der gesamten Europ\u00e4ischen Union und der nationalen Gesetzgebung (Gesetzesdekret 196\/2003, ge\u00e4ndert durch Gesetzesdekret 101\/2018) hat sich LISCIANIGIOCHI die folgenden Ziele gesetzt:&#8211; sicherstellen, dass die betroffenen Personen verstehen, welche personenbezogenen Daten gesammelt werden, f\u00fcr welche Zwecke und f\u00fcr wie lange;&#8211; klar und transparent darlegen, wie die von den Betroffenen zur Verf\u00fcgung gestellten personenbezogenen Daten verwendet werden und mit wem sie geteilt werden, um einen immer effizienteren Service anzubieten;&#8211; die betroffenen Personen \u00fcber ihre Rechte und Wahlm\u00f6glichkeiten im Zusammenhang mit der Verarbeitung personenbezogener Daten aufzukl\u00e4ren, um einerseits eine bessere Kontrolle \u00fcber sie und andererseits einen besseren Schutz seitens der an der Verarbeitung Beteiligten zu gew\u00e4hrleisten. \u00a0 Privacy f\u00fcr Minderj\u00e4hrige Die Registrierung ist nur Nutzern erlaubt, die das 18. Lebensjahr vollendet haben.LISCIANIGIOCHI S.p.A. lehnt jede Verantwortung f\u00fcr den Fall ab, dass der Benutzer falsche oder unwahre Daten angibt oder sich auf Dritte, auch Minderj\u00e4hrige, bezieht, f\u00fcr die er nicht legitimiert und\/oder ausdr\u00fccklich befugt ist, diese Daten zu \u00fcbermitteln und seine Zustimmung zur Behandlung zu geben. Der Nutzer \u00fcbernimmt die volle Verantwortung f\u00fcr ein solches Verhalten. Website-Navigation und Cookie-Richtlinie INFORMATIONEN \u00dcBER VERARBEITUNG PERSONENBEZOGENER DATEN WEBSITE UND COOKIE-RICHTLINIE gem\u00e4\u00df Art. 13 der Verordnung (EU) 2016\/679 DATENVERANTWORTLICHER UND PERS\u00d6NLICHER DATENVERARBEITER DPO LISCIANIGIOCHI S.P.A. ist der Datenverantwortliche f\u00fcr die \u00fcber die Website www.liscianigroup.com verarbeiteten personenbezogenen Daten . Der eingetragene Sitz befindet sich in Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te), P.IVA 00723030672. F\u00fcr alle Fragen zum Datenschutz wenden Sie sich bitte an die folgende E-Mail-Adresse: privacy@liscianigiochi.itoder die Telefonnummer +39 0861 2311.Der Datenschutzbeauftragte kann schriftlich an die E-Mail-Adresse dpo@liscianigiochi.it kontaktiert werden. Die Website der Institution hat folgende Adresse: https:\/\/www.liscianigroup.com BESCHREIBUNG DER VERARBEITUNG UND KATEGORIEN DERBETROFFENENPERSONENDie \u00fcber die Website erhobenen personenbezogenen Daten werden in voller \u00dcbereinstimmung mit den geltenden Rechtsvorschriften verarbeitet, wobei die Sicherheit, die Vertraulichkeit und der Schutz der in ihrem Besitz befindlichen Daten unter Wahrung der Grundrechte und -freiheiten der betroffenen Personen gem\u00e4\u00df der Europ\u00e4ischen Verordnung 2016\/679, im Folgenden GDPR genannt, gew\u00e4hrleistet werden. ART DER ERFASSTEN DATEN Die Daten werden bei der betroffenen Person erhoben. Die f\u00fcr den Betrieb dieser Website verwendeten Computersysteme und Softwareverfahren erfassen w\u00e4hrend ihres normalen Betriebs einige personenbezogene Daten, deren \u00dcbermittlung mit der Nutzung des Internets einhergeht. Zu den personenbezogenen Daten, die von dieser Website erfasst werden, geh\u00f6ren: technische, statistische und profilbildende Cookies, Daten zur Nutzung der Website, die auf der Website verbrachte Zeit. Zu den verschiedenen Informationen, die wir sammeln, geh\u00f6ren Informationen, die Sie als Person identifizieren k\u00f6nnen (&#8220;personenbezogene Daten&#8221;). Au\u00dferdem k\u00f6nnen wir &#8211; gegebenenfalls mit Ihrer Zustimmung &#8211; bestimmte Daten \u00fcber Ihr Ger\u00e4t verarbeiten, z.B. die anonymisierte IP-Adresse Ihres Ger\u00e4ts und die Aktivit\u00e4t in Bezug auf die von Ihnen genutzten Dienste. Die \u00fcber die Website verarbeiteten personenbezogenen Daten sind wie folgt: A. Automatisch erhobene Browsing-Daten: Diese Informationen werden nicht erhoben, um mit identifizierten Interessenten in Verbindung gebracht zu werden, k\u00f6nnten aber aufgrund ihrer Beschaffenheit durch die Verarbeitung und Verkn\u00fcpfung mit Daten im Besitz von Dritten die Identifizierung von Browsing-Nutzern erm\u00f6glichen. Zu dieser Datenkategorie geh\u00f6ren die &#8220;IP-Adressen&#8221; oder Domain-Namen der Computer, die von den Nutzern verwendet werden, die sich mit der Website verbinden, sowie die URI (Uniform Resource Identifier) Notationsadressen der angeforderten Ressourcen. Die IP-Adressen werden in &#8220;anonymisierter&#8221; Form gespeichert. Die sichtbaren Teile der Informationen werden ausschlie\u00dflich dazu verwendet, anonyme statistische Informationen \u00fcber die Nutzung der Website zu erhalten und das ordnungsgem\u00e4\u00dfe Funktionieren der Website von LISCIANIGIOCHI S.p.A. zu \u00fcberpr\u00fcfen. B. Cookies : Die Website verwendet einige Cookies, und die damit gesammelten Daten k\u00f6nnen f\u00fcr den Zugriff auf Teile der Website oder f\u00fcr statistische und profilbildende Zwecke verwendet werden oder um das Surfen in Zukunft angenehmer und effizienter zu gestalten, indem versucht wird, das Verhalten der Benutzer zu bewerten und das Inhaltsangebot entsprechend ihrem Verhalten zu \u00e4ndern. Weitere Informationen \u00fcber Cookies finden Sie im Abschnitt &#8220;Cookie-Richtlinie&#8221; weiter unten. C. Daten im Zusammenhang mit Websites, Diensten Dritter, Plug-Ins: Die Website kann Links zu anderen Websites oder Anwendungen enthalten. Die Website enth\u00e4lt auch Plug-ins und\/oder Schaltfl\u00e4chen f\u00fcr soziale Netzwerke, um das einfache Teilen von Inhalten in Ihren bevorzugten sozialen Netzwerken zu erm\u00f6glichen. Diese Plug-ins sind so programmiert, dass sie keine Cookies setzen, wenn Sie die Seite aufrufen, um Ihre Privatsph\u00e4re zu sch\u00fctzen. Cookies werden nur dann gesetzt, wenn dies von den sozialen Netzwerken vorgesehen ist, wenn der Benutzer das Plug-in tats\u00e4chlich und freiwillig verwendet. Bitte beachten Sie, dass, wenn der Nutzer navigiert, w\u00e4hrend er bei dem sozialen Netzwerk angemeldet ist, er der Verwendung von Cookies, die \u00fcber diese Website \u00fcbermittelt werden, bereits bei der Anmeldung bei dem sozialen Netzwerk zugestimmt hat: Die Dienste k\u00f6nnen verwendet werden, um den Verkehr dieser Website zu analysieren, der m\u00f6glicherweise pers\u00f6nliche Daten der Nutzer enth\u00e4lt, um Teile des Verkehrs, Nachrichten und Inhalte herauszufiltern, die als SPAM erkannt werden (Google reCAPTCHA, SPAM-Schutzdienst von Google Inc.). Die Sammlung und Verwendung von Informationen, die mit Hilfe von Plug-ins gewonnen werden, unterliegen den jeweiligen Datenschutzrichtlinien der sozialen Netzwerke, die Sie bitte einsehen. ZWECK DER VERARBEITUNGDieWebsite fragt bestimmte Informationen vom Browser ab, um einen qualitativ hochwertigen Service anbieten zu k\u00f6nnen. Dabei handelt es sich um Browsing-Pr\u00e4ferenzen, Logins und Cookies, die f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren der Website und f\u00fcr einen besseren Service verwendet werden. Der Data Controller kann die Daten verarbeiten, um &#8211; die Website und die Dienste zu verwalten und f\u00fcr interne Abl\u00e4ufe zu nutzen, einschlie\u00dflich der Fehlerbehebung und, wenn dies legitim ist, f\u00fcr Datenanalysen, Tests, statistische Zwecke und Umfragen; &#8211; die Website zu verbessern und daf\u00fcr zu sorgen, dass die Inhalte auf die effektivste Art und Weise pr\u00e4sentiert werden; &#8211; wenn dies legitim ist, f\u00fcr die Trendbeobachtung, das Marketing und die Werbung; &#8211; die Website sicher zu halten und f\u00fcr die Haftungsbeurteilung<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-835814","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy e cookie policy - Lisciani Giochi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy e cookie policy - Lisciani Giochi\" \/>\n<meta property=\"og:description\" content=\"Informationen \u00fcber die Verarbeitung personenbezogener Daten Warum dieses Dokument LISCIANIGIOCHI S.P.A. (im Folgenden auch LISCIANIGIOCHI, &#8220;Unternehmen&#8221; oder &#8220;Eigent\u00fcmer&#8221;) setzt sich f\u00fcr die Achtung und den Schutz der Privatsph\u00e4re ein und m\u00f6chte eine klare und transparente Vorstellung davon vermitteln, welche Informationen \u00fcber Einzelpersonen gesammelt und verarbeitet werden: Kunden und Benutzer, die auf der Website surfen, Eink\u00e4ufe t\u00e4tigen, den Newsletter abonnieren oder LISCIANIGIOCHI um Unterst\u00fctzung bitten. Nach der vollst\u00e4ndigen Umsetzung der Allgemeinen Datenschutzverordnung 2016\/679 (die sogenannte &#8220;GDPR&#8221; oder &#8220;Verordnung&#8221;) in der gesamten Europ\u00e4ischen Union und der nationalen Gesetzgebung (Gesetzesdekret 196\/2003, ge\u00e4ndert durch Gesetzesdekret 101\/2018) hat sich LISCIANIGIOCHI die folgenden Ziele gesetzt:&#8211; sicherstellen, dass die betroffenen Personen verstehen, welche personenbezogenen Daten gesammelt werden, f\u00fcr welche Zwecke und f\u00fcr wie lange;&#8211; klar und transparent darlegen, wie die von den Betroffenen zur Verf\u00fcgung gestellten personenbezogenen Daten verwendet werden und mit wem sie geteilt werden, um einen immer effizienteren Service anzubieten;&#8211; die betroffenen Personen \u00fcber ihre Rechte und Wahlm\u00f6glichkeiten im Zusammenhang mit der Verarbeitung personenbezogener Daten aufzukl\u00e4ren, um einerseits eine bessere Kontrolle \u00fcber sie und andererseits einen besseren Schutz seitens der an der Verarbeitung Beteiligten zu gew\u00e4hrleisten. \u00a0 Privacy f\u00fcr Minderj\u00e4hrige Die Registrierung ist nur Nutzern erlaubt, die das 18. Lebensjahr vollendet haben.LISCIANIGIOCHI S.p.A. lehnt jede Verantwortung f\u00fcr den Fall ab, dass der Benutzer falsche oder unwahre Daten angibt oder sich auf Dritte, auch Minderj\u00e4hrige, bezieht, f\u00fcr die er nicht legitimiert und\/oder ausdr\u00fccklich befugt ist, diese Daten zu \u00fcbermitteln und seine Zustimmung zur Behandlung zu geben. Der Nutzer \u00fcbernimmt die volle Verantwortung f\u00fcr ein solches Verhalten. Website-Navigation und Cookie-Richtlinie INFORMATIONEN \u00dcBER VERARBEITUNG PERSONENBEZOGENER DATEN WEBSITE UND COOKIE-RICHTLINIE gem\u00e4\u00df Art. 13 der Verordnung (EU) 2016\/679 DATENVERANTWORTLICHER UND PERS\u00d6NLICHER DATENVERARBEITER DPO LISCIANIGIOCHI S.P.A. ist der Datenverantwortliche f\u00fcr die \u00fcber die Website www.liscianigroup.com verarbeiteten personenbezogenen Daten . Der eingetragene Sitz befindet sich in Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te), P.IVA 00723030672. F\u00fcr alle Fragen zum Datenschutz wenden Sie sich bitte an die folgende E-Mail-Adresse: privacy@liscianigiochi.itoder die Telefonnummer +39 0861 2311.Der Datenschutzbeauftragte kann schriftlich an die E-Mail-Adresse dpo@liscianigiochi.it kontaktiert werden. Die Website der Institution hat folgende Adresse: https:\/\/www.liscianigroup.com BESCHREIBUNG DER VERARBEITUNG UND KATEGORIEN DERBETROFFENENPERSONENDie \u00fcber die Website erhobenen personenbezogenen Daten werden in voller \u00dcbereinstimmung mit den geltenden Rechtsvorschriften verarbeitet, wobei die Sicherheit, die Vertraulichkeit und der Schutz der in ihrem Besitz befindlichen Daten unter Wahrung der Grundrechte und -freiheiten der betroffenen Personen gem\u00e4\u00df der Europ\u00e4ischen Verordnung 2016\/679, im Folgenden GDPR genannt, gew\u00e4hrleistet werden. ART DER ERFASSTEN DATEN Die Daten werden bei der betroffenen Person erhoben. Die f\u00fcr den Betrieb dieser Website verwendeten Computersysteme und Softwareverfahren erfassen w\u00e4hrend ihres normalen Betriebs einige personenbezogene Daten, deren \u00dcbermittlung mit der Nutzung des Internets einhergeht. Zu den personenbezogenen Daten, die von dieser Website erfasst werden, geh\u00f6ren: technische, statistische und profilbildende Cookies, Daten zur Nutzung der Website, die auf der Website verbrachte Zeit. Zu den verschiedenen Informationen, die wir sammeln, geh\u00f6ren Informationen, die Sie als Person identifizieren k\u00f6nnen (&#8220;personenbezogene Daten&#8221;). Au\u00dferdem k\u00f6nnen wir &#8211; gegebenenfalls mit Ihrer Zustimmung &#8211; bestimmte Daten \u00fcber Ihr Ger\u00e4t verarbeiten, z.B. die anonymisierte IP-Adresse Ihres Ger\u00e4ts und die Aktivit\u00e4t in Bezug auf die von Ihnen genutzten Dienste. Die \u00fcber die Website verarbeiteten personenbezogenen Daten sind wie folgt: A. Automatisch erhobene Browsing-Daten: Diese Informationen werden nicht erhoben, um mit identifizierten Interessenten in Verbindung gebracht zu werden, k\u00f6nnten aber aufgrund ihrer Beschaffenheit durch die Verarbeitung und Verkn\u00fcpfung mit Daten im Besitz von Dritten die Identifizierung von Browsing-Nutzern erm\u00f6glichen. Zu dieser Datenkategorie geh\u00f6ren die &#8220;IP-Adressen&#8221; oder Domain-Namen der Computer, die von den Nutzern verwendet werden, die sich mit der Website verbinden, sowie die URI (Uniform Resource Identifier) Notationsadressen der angeforderten Ressourcen. Die IP-Adressen werden in &#8220;anonymisierter&#8221; Form gespeichert. Die sichtbaren Teile der Informationen werden ausschlie\u00dflich dazu verwendet, anonyme statistische Informationen \u00fcber die Nutzung der Website zu erhalten und das ordnungsgem\u00e4\u00dfe Funktionieren der Website von LISCIANIGIOCHI S.p.A. zu \u00fcberpr\u00fcfen. B. Cookies : Die Website verwendet einige Cookies, und die damit gesammelten Daten k\u00f6nnen f\u00fcr den Zugriff auf Teile der Website oder f\u00fcr statistische und profilbildende Zwecke verwendet werden oder um das Surfen in Zukunft angenehmer und effizienter zu gestalten, indem versucht wird, das Verhalten der Benutzer zu bewerten und das Inhaltsangebot entsprechend ihrem Verhalten zu \u00e4ndern. Weitere Informationen \u00fcber Cookies finden Sie im Abschnitt &#8220;Cookie-Richtlinie&#8221; weiter unten. C. Daten im Zusammenhang mit Websites, Diensten Dritter, Plug-Ins: Die Website kann Links zu anderen Websites oder Anwendungen enthalten. Die Website enth\u00e4lt auch Plug-ins und\/oder Schaltfl\u00e4chen f\u00fcr soziale Netzwerke, um das einfache Teilen von Inhalten in Ihren bevorzugten sozialen Netzwerken zu erm\u00f6glichen. Diese Plug-ins sind so programmiert, dass sie keine Cookies setzen, wenn Sie die Seite aufrufen, um Ihre Privatsph\u00e4re zu sch\u00fctzen. Cookies werden nur dann gesetzt, wenn dies von den sozialen Netzwerken vorgesehen ist, wenn der Benutzer das Plug-in tats\u00e4chlich und freiwillig verwendet. Bitte beachten Sie, dass, wenn der Nutzer navigiert, w\u00e4hrend er bei dem sozialen Netzwerk angemeldet ist, er der Verwendung von Cookies, die \u00fcber diese Website \u00fcbermittelt werden, bereits bei der Anmeldung bei dem sozialen Netzwerk zugestimmt hat: Die Dienste k\u00f6nnen verwendet werden, um den Verkehr dieser Website zu analysieren, der m\u00f6glicherweise pers\u00f6nliche Daten der Nutzer enth\u00e4lt, um Teile des Verkehrs, Nachrichten und Inhalte herauszufiltern, die als SPAM erkannt werden (Google reCAPTCHA, SPAM-Schutzdienst von Google Inc.). Die Sammlung und Verwendung von Informationen, die mit Hilfe von Plug-ins gewonnen werden, unterliegen den jeweiligen Datenschutzrichtlinien der sozialen Netzwerke, die Sie bitte einsehen. ZWECK DER VERARBEITUNGDieWebsite fragt bestimmte Informationen vom Browser ab, um einen qualitativ hochwertigen Service anbieten zu k\u00f6nnen. Dabei handelt es sich um Browsing-Pr\u00e4ferenzen, Logins und Cookies, die f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren der Website und f\u00fcr einen besseren Service verwendet werden. Der Data Controller kann die Daten verarbeiten, um &#8211; die Website und die Dienste zu verwalten und f\u00fcr interne Abl\u00e4ufe zu nutzen, einschlie\u00dflich der Fehlerbehebung und, wenn dies legitim ist, f\u00fcr Datenanalysen, Tests, statistische Zwecke und Umfragen; &#8211; die Website zu verbessern und daf\u00fcr zu sorgen, dass die Inhalte auf die effektivste Art und Weise pr\u00e4sentiert werden; &#8211; wenn dies legitim ist, f\u00fcr die Trendbeobachtung, das Marketing und die Werbung; &#8211; die Website sicher zu halten und f\u00fcr die Haftungsbeurteilung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Lisciani Giochi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/liscianigroup\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T08:25:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"75 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/\",\"url\":\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/\",\"name\":\"Privacy e cookie policy - Lisciani Giochi\",\"isPartOf\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\",\"datePublished\":\"2024-06-29T10:58:05+00:00\",\"dateModified\":\"2025-05-09T08:25:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#primaryimage\",\"url\":\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\",\"contentUrl\":\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.liscianigiochi.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy e cookie policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.liscianigiochi.com\/#website\",\"url\":\"https:\/\/www.liscianigiochi.com\/\",\"name\":\"Lisciani Giochi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.liscianigiochi.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.liscianigiochi.com\/#organization\",\"name\":\"Lisciani Giochi\",\"url\":\"https:\/\/www.liscianigiochi.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png\",\"contentUrl\":\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png\",\"width\":384,\"height\":384,\"caption\":\"Lisciani Giochi\"},\"image\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/liscianigroup\",\"https:\/\/www.instagram.com\/liscianigiochi\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy e cookie policy - Lisciani Giochi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/","og_locale":"de_DE","og_type":"article","og_title":"Privacy e cookie policy - Lisciani Giochi","og_description":"Informationen \u00fcber die Verarbeitung personenbezogener Daten Warum dieses Dokument LISCIANIGIOCHI S.P.A. (im Folgenden auch LISCIANIGIOCHI, &#8220;Unternehmen&#8221; oder &#8220;Eigent\u00fcmer&#8221;) setzt sich f\u00fcr die Achtung und den Schutz der Privatsph\u00e4re ein und m\u00f6chte eine klare und transparente Vorstellung davon vermitteln, welche Informationen \u00fcber Einzelpersonen gesammelt und verarbeitet werden: Kunden und Benutzer, die auf der Website surfen, Eink\u00e4ufe t\u00e4tigen, den Newsletter abonnieren oder LISCIANIGIOCHI um Unterst\u00fctzung bitten. Nach der vollst\u00e4ndigen Umsetzung der Allgemeinen Datenschutzverordnung 2016\/679 (die sogenannte &#8220;GDPR&#8221; oder &#8220;Verordnung&#8221;) in der gesamten Europ\u00e4ischen Union und der nationalen Gesetzgebung (Gesetzesdekret 196\/2003, ge\u00e4ndert durch Gesetzesdekret 101\/2018) hat sich LISCIANIGIOCHI die folgenden Ziele gesetzt:&#8211; sicherstellen, dass die betroffenen Personen verstehen, welche personenbezogenen Daten gesammelt werden, f\u00fcr welche Zwecke und f\u00fcr wie lange;&#8211; klar und transparent darlegen, wie die von den Betroffenen zur Verf\u00fcgung gestellten personenbezogenen Daten verwendet werden und mit wem sie geteilt werden, um einen immer effizienteren Service anzubieten;&#8211; die betroffenen Personen \u00fcber ihre Rechte und Wahlm\u00f6glichkeiten im Zusammenhang mit der Verarbeitung personenbezogener Daten aufzukl\u00e4ren, um einerseits eine bessere Kontrolle \u00fcber sie und andererseits einen besseren Schutz seitens der an der Verarbeitung Beteiligten zu gew\u00e4hrleisten. \u00a0 Privacy f\u00fcr Minderj\u00e4hrige Die Registrierung ist nur Nutzern erlaubt, die das 18. Lebensjahr vollendet haben.LISCIANIGIOCHI S.p.A. lehnt jede Verantwortung f\u00fcr den Fall ab, dass der Benutzer falsche oder unwahre Daten angibt oder sich auf Dritte, auch Minderj\u00e4hrige, bezieht, f\u00fcr die er nicht legitimiert und\/oder ausdr\u00fccklich befugt ist, diese Daten zu \u00fcbermitteln und seine Zustimmung zur Behandlung zu geben. Der Nutzer \u00fcbernimmt die volle Verantwortung f\u00fcr ein solches Verhalten. Website-Navigation und Cookie-Richtlinie INFORMATIONEN \u00dcBER VERARBEITUNG PERSONENBEZOGENER DATEN WEBSITE UND COOKIE-RICHTLINIE gem\u00e4\u00df Art. 13 der Verordnung (EU) 2016\/679 DATENVERANTWORTLICHER UND PERS\u00d6NLICHER DATENVERARBEITER DPO LISCIANIGIOCHI S.P.A. ist der Datenverantwortliche f\u00fcr die \u00fcber die Website www.liscianigroup.com verarbeiteten personenbezogenen Daten . Der eingetragene Sitz befindet sich in Via Giacomo Ruscitti, Zona Ind.le Sant&#8217;Atto, 64100 Teramo (Te), P.IVA 00723030672. F\u00fcr alle Fragen zum Datenschutz wenden Sie sich bitte an die folgende E-Mail-Adresse: privacy@liscianigiochi.itoder die Telefonnummer +39 0861 2311.Der Datenschutzbeauftragte kann schriftlich an die E-Mail-Adresse dpo@liscianigiochi.it kontaktiert werden. Die Website der Institution hat folgende Adresse: https:\/\/www.liscianigroup.com BESCHREIBUNG DER VERARBEITUNG UND KATEGORIEN DERBETROFFENENPERSONENDie \u00fcber die Website erhobenen personenbezogenen Daten werden in voller \u00dcbereinstimmung mit den geltenden Rechtsvorschriften verarbeitet, wobei die Sicherheit, die Vertraulichkeit und der Schutz der in ihrem Besitz befindlichen Daten unter Wahrung der Grundrechte und -freiheiten der betroffenen Personen gem\u00e4\u00df der Europ\u00e4ischen Verordnung 2016\/679, im Folgenden GDPR genannt, gew\u00e4hrleistet werden. ART DER ERFASSTEN DATEN Die Daten werden bei der betroffenen Person erhoben. Die f\u00fcr den Betrieb dieser Website verwendeten Computersysteme und Softwareverfahren erfassen w\u00e4hrend ihres normalen Betriebs einige personenbezogene Daten, deren \u00dcbermittlung mit der Nutzung des Internets einhergeht. Zu den personenbezogenen Daten, die von dieser Website erfasst werden, geh\u00f6ren: technische, statistische und profilbildende Cookies, Daten zur Nutzung der Website, die auf der Website verbrachte Zeit. Zu den verschiedenen Informationen, die wir sammeln, geh\u00f6ren Informationen, die Sie als Person identifizieren k\u00f6nnen (&#8220;personenbezogene Daten&#8221;). Au\u00dferdem k\u00f6nnen wir &#8211; gegebenenfalls mit Ihrer Zustimmung &#8211; bestimmte Daten \u00fcber Ihr Ger\u00e4t verarbeiten, z.B. die anonymisierte IP-Adresse Ihres Ger\u00e4ts und die Aktivit\u00e4t in Bezug auf die von Ihnen genutzten Dienste. Die \u00fcber die Website verarbeiteten personenbezogenen Daten sind wie folgt: A. Automatisch erhobene Browsing-Daten: Diese Informationen werden nicht erhoben, um mit identifizierten Interessenten in Verbindung gebracht zu werden, k\u00f6nnten aber aufgrund ihrer Beschaffenheit durch die Verarbeitung und Verkn\u00fcpfung mit Daten im Besitz von Dritten die Identifizierung von Browsing-Nutzern erm\u00f6glichen. Zu dieser Datenkategorie geh\u00f6ren die &#8220;IP-Adressen&#8221; oder Domain-Namen der Computer, die von den Nutzern verwendet werden, die sich mit der Website verbinden, sowie die URI (Uniform Resource Identifier) Notationsadressen der angeforderten Ressourcen. Die IP-Adressen werden in &#8220;anonymisierter&#8221; Form gespeichert. Die sichtbaren Teile der Informationen werden ausschlie\u00dflich dazu verwendet, anonyme statistische Informationen \u00fcber die Nutzung der Website zu erhalten und das ordnungsgem\u00e4\u00dfe Funktionieren der Website von LISCIANIGIOCHI S.p.A. zu \u00fcberpr\u00fcfen. B. Cookies : Die Website verwendet einige Cookies, und die damit gesammelten Daten k\u00f6nnen f\u00fcr den Zugriff auf Teile der Website oder f\u00fcr statistische und profilbildende Zwecke verwendet werden oder um das Surfen in Zukunft angenehmer und effizienter zu gestalten, indem versucht wird, das Verhalten der Benutzer zu bewerten und das Inhaltsangebot entsprechend ihrem Verhalten zu \u00e4ndern. Weitere Informationen \u00fcber Cookies finden Sie im Abschnitt &#8220;Cookie-Richtlinie&#8221; weiter unten. C. Daten im Zusammenhang mit Websites, Diensten Dritter, Plug-Ins: Die Website kann Links zu anderen Websites oder Anwendungen enthalten. Die Website enth\u00e4lt auch Plug-ins und\/oder Schaltfl\u00e4chen f\u00fcr soziale Netzwerke, um das einfache Teilen von Inhalten in Ihren bevorzugten sozialen Netzwerken zu erm\u00f6glichen. Diese Plug-ins sind so programmiert, dass sie keine Cookies setzen, wenn Sie die Seite aufrufen, um Ihre Privatsph\u00e4re zu sch\u00fctzen. Cookies werden nur dann gesetzt, wenn dies von den sozialen Netzwerken vorgesehen ist, wenn der Benutzer das Plug-in tats\u00e4chlich und freiwillig verwendet. Bitte beachten Sie, dass, wenn der Nutzer navigiert, w\u00e4hrend er bei dem sozialen Netzwerk angemeldet ist, er der Verwendung von Cookies, die \u00fcber diese Website \u00fcbermittelt werden, bereits bei der Anmeldung bei dem sozialen Netzwerk zugestimmt hat: Die Dienste k\u00f6nnen verwendet werden, um den Verkehr dieser Website zu analysieren, der m\u00f6glicherweise pers\u00f6nliche Daten der Nutzer enth\u00e4lt, um Teile des Verkehrs, Nachrichten und Inhalte herauszufiltern, die als SPAM erkannt werden (Google reCAPTCHA, SPAM-Schutzdienst von Google Inc.). Die Sammlung und Verwendung von Informationen, die mit Hilfe von Plug-ins gewonnen werden, unterliegen den jeweiligen Datenschutzrichtlinien der sozialen Netzwerke, die Sie bitte einsehen. ZWECK DER VERARBEITUNGDieWebsite fragt bestimmte Informationen vom Browser ab, um einen qualitativ hochwertigen Service anbieten zu k\u00f6nnen. Dabei handelt es sich um Browsing-Pr\u00e4ferenzen, Logins und Cookies, die f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren der Website und f\u00fcr einen besseren Service verwendet werden. Der Data Controller kann die Daten verarbeiten, um &#8211; die Website und die Dienste zu verwalten und f\u00fcr interne Abl\u00e4ufe zu nutzen, einschlie\u00dflich der Fehlerbehebung und, wenn dies legitim ist, f\u00fcr Datenanalysen, Tests, statistische Zwecke und Umfragen; &#8211; die Website zu verbessern und daf\u00fcr zu sorgen, dass die Inhalte auf die effektivste Art und Weise pr\u00e4sentiert werden; &#8211; wenn dies legitim ist, f\u00fcr die Trendbeobachtung, das Marketing und die Werbung; &#8211; die Website sicher zu halten und f\u00fcr die Haftungsbeurteilung","og_url":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/","og_site_name":"Lisciani Giochi","article_publisher":"https:\/\/www.facebook.com\/liscianigroup","article_modified_time":"2025-05-09T08:25:23+00:00","og_image":[{"url":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"75 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/","url":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/","name":"Privacy e cookie policy - Lisciani Giochi","isPartOf":{"@id":"https:\/\/www.liscianigiochi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#primaryimage"},"image":{"@id":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png","datePublished":"2024-06-29T10:58:05+00:00","dateModified":"2025-05-09T08:25:23+00:00","breadcrumb":{"@id":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#primaryimage","url":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png","contentUrl":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2024\/10\/icon-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.liscianigiochi.com\/privacy-e-cookie-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.liscianigiochi.com\/de\/"},{"@type":"ListItem","position":2,"name":"Privacy e cookie policy"}]},{"@type":"WebSite","@id":"https:\/\/www.liscianigiochi.com\/#website","url":"https:\/\/www.liscianigiochi.com\/","name":"Lisciani Giochi","description":"","publisher":{"@id":"https:\/\/www.liscianigiochi.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.liscianigiochi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.liscianigiochi.com\/#organization","name":"Lisciani Giochi","url":"https:\/\/www.liscianigiochi.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png","contentUrl":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png","width":384,"height":384,"caption":"Lisciani Giochi"},"image":{"@id":"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/liscianigroup","https:\/\/www.instagram.com\/liscianigiochi\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/pages\/835814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/comments?post=835814"}],"version-history":[{"count":4,"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/pages\/835814\/revisions"}],"predecessor-version":[{"id":1299572,"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/pages\/835814\/revisions\/1299572"}],"wp:attachment":[{"href":"https:\/\/www.liscianigiochi.com\/de\/wp-json\/wp\/v2\/media?parent=835814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}