{"id":669958,"date":"2024-07-03T10:50:28","date_gmt":"2024-07-03T08:50:28","guid":{"rendered":"https:\/\/www.liscianigiochi.com\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/"},"modified":"2026-05-08T06:12:58","modified_gmt":"2026-05-08T04:12:58","slug":"disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en","status":"publish","type":"product","link":"https:\/\/www.liscianigiochi.com\/en\/shop\/puzzles-for-children-en\/puzzle-maxifloor-108-en\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/","title":{"rendered":"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia"},"content":{"rendered":"<p>Have fun reconstructing the most beautiful scenes of your favourite characters and, after completing the puzzle, the fun continues! On the back of the board you will find a black and white scene to colour in!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reconstruct and color the most beautiful scenes from your favorite cartoons!<\/p>\n","protected":false},"featured_media":1832594,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2819,2787],"product_tag":[3021,3023,3035,3029],"class_list":{"0":"post-669958","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-puzzle-maxifloor-108-en","7":"product_cat-puzzles-for-children-en","8":"product_tag-3-4-years-en","9":"product_tag-5-6-years-en","10":"product_tag-disney-giocattolo-en","11":"product_tag-disney-princess-en","13":"first","14":"instock","15":"shipping-taxable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disney Puzzle Df Maxi Floor 108 Bella E La Bestia - Liscianigiochi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia - Liscianigiochi\" \/>\n<meta property=\"og:description\" content=\"Reconstruct and color the most beautiful scenes from your favorite cartoons!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Liscianigiochi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/liscianigroup\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T04:12:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/\",\"url\":\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/\",\"name\":\"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia - Liscianigiochi\",\"isPartOf\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg\",\"datePublished\":\"2024-07-03T08:50:28+00:00\",\"dateModified\":\"2026-05-08T04:12:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#primaryimage\",\"url\":\"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg\",\"contentUrl\":\"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.liscianigiochi.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/lg.udnt.it\/en\/store\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.liscianigiochi.com\/#website\",\"url\":\"https:\/\/www.liscianigiochi.com\/\",\"name\":\"Lisciani Giochi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.liscianigiochi.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.liscianigiochi.com\/#organization\",\"name\":\"Lisciani Giochi\",\"url\":\"https:\/\/www.liscianigiochi.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png\",\"contentUrl\":\"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png\",\"width\":384,\"height\":384,\"caption\":\"Lisciani Giochi\"},\"image\":{\"@id\":\"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/liscianigroup\",\"https:\/\/www.instagram.com\/liscianigiochi\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia - Liscianigiochi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/","og_locale":"en_US","og_type":"article","og_title":"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia - Liscianigiochi","og_description":"Reconstruct and color the most beautiful scenes from your favorite cartoons!","og_url":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/","og_site_name":"Liscianigiochi","article_publisher":"https:\/\/www.facebook.com\/liscianigroup","article_modified_time":"2026-05-08T04:12:58+00:00","og_image":[{"url":"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/","url":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/","name":"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia - Liscianigiochi","isPartOf":{"@id":"https:\/\/www.liscianigiochi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#primaryimage"},"image":{"@id":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#primaryimage"},"thumbnailUrl":"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg","datePublished":"2024-07-03T08:50:28+00:00","dateModified":"2026-05-08T04:12:58+00:00","breadcrumb":{"@id":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#primaryimage","url":"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg","contentUrl":"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.liscianigiochi.com\/en\/shop\/uncategorized\/disney-puzzle-df-maxi-floor-108-bella-e-la-bestia-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.liscianigiochi.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lg.udnt.it\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Disney Puzzle Df Maxi Floor 108 Bella E La Bestia"}]},{"@type":"WebSite","@id":"https:\/\/www.liscianigiochi.com\/#website","url":"https:\/\/www.liscianigiochi.com\/","name":"Lisciani Giochi","description":"","publisher":{"@id":"https:\/\/www.liscianigiochi.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.liscianigiochi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.liscianigiochi.com\/#organization","name":"Lisciani Giochi","url":"https:\/\/www.liscianigiochi.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png","contentUrl":"https:\/\/www.liscianigiochi.com\/wp-content\/uploads\/2023\/10\/Logo@2x.png","width":384,"height":384,"caption":"Lisciani Giochi"},"image":{"@id":"https:\/\/www.liscianigiochi.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/liscianigroup","https:\/\/www.instagram.com\/liscianigiochi\/"]}]}},"fifu_image_url":"https:\/\/mf.liscianigiochi.it:8443\/media\/91775\/0DE21427-0DE2-4F9E-BD6D-D1D8FF7024AD.jpg","_links":{"self":[{"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/product\/669958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/media\/1832594"}],"wp:attachment":[{"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/media?parent=669958"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/product_brand?post=669958"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/product_cat?post=669958"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.liscianigiochi.com\/en\/wp-json\/wp\/v2\/product_tag?post=669958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}